{"id":2305,"date":"2018-03-30T15:06:08","date_gmt":"2018-03-30T19:06:08","guid":{"rendered":"https:\/\/solidedge.siemens.com\/medical-devices\/"},"modified":"2019-09-03T14:11:45","modified_gmt":"2019-09-03T18:11:45","slug":"medical-devices","status":"publish","type":"page","link":"https:\/\/solidedge.siemens.com\/pt-br\/industries\/medical-devices\/","title":{"rendered":"Dispositivos m\u00e9dicos"},"content":{"rendered":"<p>[vc_row full_width=&#8221;stretch_row&#8221; full_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; css=&#8221;.vc_custom_1524845057022{background: #a6a6a6 url(https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2018\/04\/vc-bg-hero-banner-medical-devices.jpg?id=844) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221; el_class=&#8221;vc-row-hero-banner&#8221;][vc_column][vc_column_text el_class=&#8221;.vc-el-callout&#8221;]<\/p>\n<h1>Projeto de Dispositivos M\u00e9dicos<\/h1>\n<p>Desenvolver dispositivos m\u00e9dicos inovadores e de alta qualidade com mais rapidez que a concorr\u00eancia<\/p>\n<p><a class=\"action-button\" href=\"\/pt-br\/try-now\/\"><i class=\"icon-ext\"><\/i>Teste Gratuita do Solid Edge<\/a>[\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1524163183110{background-color: #ebf0f4 !important;}&#8221; el_class=&#8221;vc-row-industry-insights&#8221;][vc_column width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;842&#8243; img_size=&#8221;industry-insight&#8221; alignment=&#8221;center&#8221;][\/vc_column][vc_column width=&#8221;2\/3&#8243; offset=&#8221;vc_col-md-offset-1 vc_col-md-7&#8243;][vc_column_text el_class=&#8221;vc-el-lead-in&#8221;]<\/p>\n<p>Insights da Ind\u00fastria<\/p>\n<h2>Lograr dispositivos m\u00e9dicos mais r\u00e1pidos e eficientes com o Solid Edge<\/h2>\n<p>O software Solid Edge pode acelerar o desenvolvimento de produtos e realizar testes e an\u00e1lises virtuais de projetos para garantir que os novos produtos atendam \u00e0s necessidades do cliente e aos requisitos regulamentares.<\/p>\n<p><a class=\"action-button\" href=\"https:\/\/www.plm.automation.siemens.com\/en_us\/Images\/Siemens-PLM-Accelerate-Medical-Device-Design-With-Solid-Edge-sb_tcm1023-237262.pdf\"><i class=\"icon-ext\"><\/i>Saiba mais<\/a><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row el_class=&#8221;vc-row-text-icon-checklist&#8221;][vc_column][vc_column_text el_class=&#8221;vc-el-lead-in&#8221;]Vis\u00e3o Geral<\/p>\n<h1>Acelerar o Processo de<br \/>\nProjeto de Dispositivos M\u00e9dicos<\/h1>\n<p>[\/vc_column_text][vc_row_inner content_placement=&#8221;middle&#8221;][vc_column_inner width=&#8221;5\/6&#8243;][vc_column_text]Os fabricantes de dispositivos m\u00e9dicos necessitam acelerar o desenvolvimento de produtos inovadores e de alta qualidade para  m\u00e9dicos , pacientes , em conformidade com todas as regulamenta\u00e7\u00f5es governamentais relevantes.<\/p>\n<p>O Solid Edge fornece solu\u00e7\u00f5es poderosas e f\u00e1ceis de usar para o design de dispositivos m\u00e9dicos que ajudam a atender a essas necessidades. Ao utilizar o Solid Edge, independente do seu porte como fabricante de dispositivos m\u00e9dicos, voc\u00ea pode aprimorar  seus processos de design e desenvolvimento, oferecendo produtos de alta qualidade no momento adequado , aument o fluxo de caixa e as margens de lucro.<\/p>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;][vc_single_image image=&#8221;428&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; el_class=&#8221;vc-el-vector-icon inline-me&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; bg_type=&#8221;image&#8221; enable_overlay=&#8221;enable_overlay_value&#8221; overlay_color=&#8221;rgba(0,0,0,0.4)&#8221; el_class=&#8221;vc-row-hero-advantages vc-row-match-bg-height&#8221; css=&#8221;.vc_custom_1524845846204{background: #a6a6a6 url(https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2018\/04\/vc-bg-advantages-medical-devices.jpg?id=845) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_column][vc_column_text el_class=&#8221;vc-el-lead-in&#8221;]Capacidades<\/p>\n<h1>A vantagem do Solid Edge<\/h1>\n<p>O Solid Edge pode acelerar o design de dispositivos m\u00e9dicos e ajudar sua empresa a prosperar nesse exigente ambiente de fabrica\u00e7\u00e3o com:[\/vc_column_text][vc_row_inner equal_height=&#8221;yes&#8221; el_class=&#8221;vc-row-checkmark-text-blocks&#8221;][vc_column_inner width=&#8221;1\/2&#8243; offset=&#8221;vc_col-md-4&#8243;][vc_column_text]<strong>Digitalizar processos de engenharia. <\/strong>Digitalize seu processo de desenvolvimento de produtos e transforme seu neg\u00f3cio Simplifique processos de engenharia com modelos digitais 3D. Adicione intelig\u00eancia a modelos 3D em todo o ciclo de vida do desenvolvimento do produto.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243; offset=&#8221;vc_col-md-4&#8243;][vc_column_text]<strong>Melhore a produtividade com o projeto de pr\u00f3xima gera\u00e7\u00e3o do <span> <a href=\"https:\/\/solidedge.siemens.com\/pt-br\/solutions\/products\/3d-design\/next-generation-design\/\">. <\/a> \u00a0<\/span><\/strong>Fa\u00e7a representa\u00e7\u00f5es digitais de projetos existentes com o <span> <a href=\"https:\/\/solidedge.siemens.com\/pt-br\/solutions\/products\/3d-design\/next-generation-design\/reverse-engineering\/\"> Engineering reverso <\/a> <\/span>. Use o <span> <a href=\"https:\/\/solidedge.siemens.com\/pt-br\/?page_id=300\"> modelagem de montagem <\/a> <\/span> para gerenciar grandes montagens, at\u00e9 100.000 pe\u00e7as. Otimize os produtos com o <span> <a href=\"https:\/\/solidedge.siemens.com\/pt-br\/solutions\/products\/3d-design\/next-generation-design\/generative-design\/\"> Design gerativo <\/a> <\/span>.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243; offset=&#8221;vc_col-md-4&#8243;][vc_column_text]<strong>Acelere o projeto mec\u00e2nico com CAD 3D. <\/strong>Use uma abordagem sem hist\u00f3rico para CAD 3D com <span> <a href=\"https:\/\/solidedge.siemens.com\/pt-br\/solutions\/products\/3d-design\/synchronous-technology\/\"> Synchronous Technology <\/a> <\/span>. Projetar pe\u00e7as e montagens complexas de maneira r\u00e1pida e flex\u00edvel usando a tecnologia s\u00edncrona. Trabalhe diretamente com a geometria de projeto e fa\u00e7a altera\u00e7\u00f5es instantaneamente.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243; offset=&#8221;vc_col-md-4&#8243;][vc_column_text]<strong>Capture a inten\u00e7\u00e3o do projeto. <\/strong>Crie imagens e anima\u00e7\u00f5es fotorealistas de produtos propostos com <span> <a href=\"https:\/\/solidedge.siemens.com\/pt-br\/solutions\/products\/3d-design\/industrial-design-software\/3d-rendering\/\"> renderiza\u00e7\u00e3o 3D <\/a> <\/span>. Comunique o valor de novos produtos a clientes potenciais. Validar projeto em configura\u00e7\u00f5es do mundo real usando <span> <a href=\"https:\/\/solidedge.siemens.com\/pt-br\/solutions\/products\/cloud-based-collaboration\/teamcenter-share\/augmented-reality\/\"> realidade aumentada <\/a> <\/span>.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243; offset=&#8221;vc_col-md-4&#8243;][vc_column_text]<strong>Projeto Eletromec\u00e2nico Integrado (NX). <\/strong>Crie projetos totalmente funcionais e manufaturados usando recursos comprovados do <span> <a href=\"https:\/\/solidedge.siemens.com\/pt-br\/solutions\/products\/electrical-design\/\"> de fia\u00e7\u00e3o e chicotes <\/a> <\/span>. Habilite a colabora\u00e7\u00e3o ECAD-MCAD cont\u00ednua para engenheiros el\u00e9tricos e mec\u00e2nicos.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243; offset=&#8221;vc_col-md-4&#8243;][vc_column_text]<strong>Projeto para impress\u00e3o 3D. <\/strong>Crie produtos usando as t\u00e9cnicas mais recentes do <span> <a href=\"https:\/\/solidedge.siemens.com\/pt-br\/solutions\/products\/computer-aided-manufacturing-cam\/additive-manufacturing\/\"> Manufacturing aditiva <\/a> <\/span> e <span> <a href=\"https:\/\/solidedge.siemens.com\/pt-br\/solutions\/products\/3d-printing\/\"> Printing 3D <\/a> <\/span>, com suporte para um fluxo de trabalho de ponta a ponta.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243; offset=&#8221;vc_col-md-4&#8243;][vc_column_text]<strong>Crie facilmente modelos de pe\u00e7a em chapa. <\/strong>Crie modelos 3D <span><a href=\"https:\/\/solidedge.siemens.com\/pt-br\/solutions\/products\/3d-design\/sheet-metal-design\/\"> Sheet metal <\/a><\/span> a partir de rascunhos 2D. Use fun\u00e7\u00f5es \u00fanicas, como flanges loft aprimorados e al\u00edvio de protuber\u00e2ncia de dobra, para construir modelos complexos.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243; offset=&#8221;vc_col-md-4&#8243;][vc_column_text]<strong>Satisfa\u00e7am os requisitos comerciais e de regulamenta\u00e7\u00e3o. <\/strong>Gerencie os requisitos de cliente e regulamenta\u00e7\u00e3o usando o <span><a href=\"https:\/\/solidedge.siemens.com\/pt-br\/solutions\/products\/data-management\/requirements-management\/\"> Management requirements <\/a><\/span>. Torne os requisitos facilmente vis\u00edveis para projetar engenheiros e acompanhe o cumprimento desses requisitos.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243; offset=&#8221;vc_col-md-4&#8243;][vc_column_text]<strong>Habilitar documenta\u00e7\u00e3o 3D sem papel. <\/strong><span><a href=\"https:\/\/solidedge.siemens.com\/pt-br\/solutions\/products\/3d-design\/model-based-definition\/\"><\/a><\/span>Comunique com mais efici\u00eancia e reduza os custos de manufatura usando modelos 3D anotados em vez de desenhos 2D com defini\u00e7\u00e3o baseada em modelo   do . Gaste menos tempo na documenta\u00e7\u00e3o.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243; offset=&#8221;vc_col-md-4&#8243;][vc_column_text]<strong>Validar e melhorar o desempenho do produto. <\/strong>Validar e melhorar o desempenho de produtos com <span> dimension\u00e1vel <a href=\"https:\/\/solidedge.siemens.com\/pt-br\/solutions\/products\/simulation\/solid-edge-simulation\/\"> Simulation <\/a> <\/span> Tools que usam prot\u00f3tipos virtuais e novas simula\u00e7\u00f5es de movimento e vibra\u00e7\u00e3o integradas. Comunique sua documenta\u00e7\u00e3o de projeto digital globalmente com a tradu\u00e7\u00e3o de idioma do XLIFF.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243; offset=&#8221;vc_col-md-4&#8243;][vc_column_text]<strong>Colabore no projeto PCB. <\/strong>Use a captura esquem\u00e1tica do setor e as ferramentas de layout <span> <a href=\"https:\/\/solidedge.siemens.com\/pt-br\/solutions\/products\/electrical-design\/pcb-design\/\"> PCB <\/a> <\/span> para evitar redesenho dispendioso. Habilitar a colabora\u00e7\u00e3o em tempo real entre as equipes do ECAD-MCAD para superar desafios eletromec\u00e2nicos.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243; offset=&#8221;vc_col-md-4&#8243;][vc_column_text]<strong>Compartilhe dados do produto sobre a nuvem. <\/strong><span> <a href=\"https:\/\/solidedge.siemens.com\/pt-br\/solutions\/initiatives\/cloud-ready-design\/\"> A colabora\u00e7\u00e3o baseada em nuvem <\/a> <\/span> oferece uma maneira segura de compartilhar informa\u00e7\u00f5es de produto independentemente da origem.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243; offset=&#8221;vc_col-md-4&#8243;][vc_column_text]<strong>Gerencie dados de forma f\u00e1cil e segura. <\/strong>Pesquise, gerencie e compartilhe dados de produtos de maneira eficiente e segura com solu\u00e7\u00f5es de gerenciamento de dados escal\u00e1veis. Atenda \u00e0s necessidades de todos os fabricantes com o built-in <span> <a href=\"https:\/\/solidedge.siemens.com\/pt-br\/solutions\/products\/data-management\/requirements-management\/\"> gerenciamento de dados <\/a> <\/span> e <span> <a href=\"https:\/\/solidedge.siemens.com\/pt-br\/solutions\/products\/data-management\/teamcenter-integration-for-solid-edge\/\"> Teamcenter Integration. <\/a> <\/span>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_column_text]<\/p>\n<p class=\"f-very-large\">Com recursos de CAD 3D, simula\u00e7\u00e3o, manufatura e gerenciamento de projeto, o Solid Edge fornece um portf\u00f3lio integrado de solu\u00e7\u00f5es acess\u00edveis e f\u00e1ceis de usar que ajudam as empresas de fabrica\u00e7\u00e3o de dispositivos m\u00e9dicos a melhorarem seus projetos.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; el_class=&#8221;vc-row-video-story-overview&#8221; css=&#8221;.vc_custom_1524845983242{background-color: #ebf0f4 !important;}&#8221;][vc_column][vc_column_text el_class=&#8221;vc-el-lead-in&#8221;]Destaque do Cliente<\/p>\n<h2>Design Mais R\u00e1pido de Equipamento Avan\u00e7ado de Neurocirurgia<\/h2>\n<p>O Solid Edge acelera o design de equipamento de neurocirurgia da pr\u00f3xima gera\u00e7\u00e3o, reduzindo prazo de 12 para 5 meses e proporcionando um dispositivo f\u00e1cil de usar, compacto l.[\/vc_column_text]\n\n\n  <div id=\"wpv-view-layout-567-CATTR0467ad1d339c535987324491956a908d\" class=\"js-wpv-view-layout js-wpv-layout-responsive js-wpv-view-layout-567-CATTR0467ad1d339c535987324491956a908d\" data-viewnumber=\"567-CATTR0467ad1d339c535987324491956a908d\" data-pagination=\"{&quot;id&quot;:567,&quot;query&quot;:&quot;normal&quot;,&quot;type&quot;:&quot;disabled&quot;,&quot;effect&quot;:&quot;fade&quot;,&quot;duration&quot;:500,&quot;speed&quot;:5,&quot;pause_on_hover&quot;:&quot;disabled&quot;,&quot;stop_rollover&quot;:&quot;false&quot;,&quot;cache_pages&quot;:&quot;enabled&quot;,&quot;preload_images&quot;:&quot;enabled&quot;,&quot;preload_pages&quot;:&quot;enabled&quot;,&quot;preload_reach&quot;:1,&quot;spinner&quot;:&quot;builtin&quot;,&quot;spinner_image&quot;:&quot;https:\/\/solidedge.siemens.com\/wp-content\/plugins\/wp-views\/embedded\/res\/img\/ajax-loader.gif&quot;,&quot;callback_next&quot;:&quot;&quot;,&quot;manage_history&quot;:&quot;disabled&quot;,&quot;has_controls_in_form&quot;:&quot;disabled&quot;,&quot;infinite_tolerance&quot;:&quot;0&quot;,&quot;max_pages&quot;:0,&quot;page&quot;:1,&quot;base_permalink&quot;:&quot;\/pt-br\/wp-json\/wp\/v2\/pages\/2305?wpv_view_count=567-CATTR0467ad1d339c535987324491956a908d&amp;wpv_paged=WPV_PAGE_NUM&quot;,&quot;loop&quot;:{&quot;type&quot;:&quot;&quot;,&quot;name&quot;:&quot;&quot;,&quot;data&quot;:[],&quot;id&quot;:0}}\" data-permalink=\"\/pt-br\/wp-json\/wp\/v2\/pages\/2305?wpv_view_count=567-CATTR0467ad1d339c535987324491956a908d\">\n\n  \n  <div class=\"wpv-resources\"><a name=\"video\" class=\"video-anchor\"><\/a>\n    <div id=\"ult-carousel-2350906936a04642a442f2\" class=\"ult-carousel-wrapper  vc-el-carousel-videos-embedded ult_horizontal\" data-gutter=\"0\" data-rtl=\"false\" ><div class=\"ult-carousel-2117653226a04642a442ce \" >\n    \n    \n       <div><!-- slide container -->\n        <div class=\"wpv-resources-item\" data-mh=\".wpv-resources-item\">\n          <div class=\"resources-item-poster\">\n              <div id=\"wpfp_c506682932a548c36a3e4686f1805cf8\" data-item=\"{&quot;sources&quot;:&#091;{&quot;src&quot;:&quot;https:\\\/\\\/media.plm.automation.siemens.com\\\/success\\\/AlphaOmega-44404.mp4&quot;,&quot;type&quot;:&quot;video\\\/mp4&quot;}&#093;}\" class=\"flowplayer no-brand is-splash no-svg is-paused skin-slim fp-slim fp-edgy\" data-embed=\"false\" style=\"max-width: 1140px; max-height: 640px; background-image: url(https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2018\/04\/c-alpha-omega.jpg);\" data-ratio=\"0.5614\" data-advance=\"false\">\n\t<div class=\"fp-ratio\" style=\"padding-top: 56.14%\"><\/div>\n\t<div class=\"fp-ui\"><div class=\"fp-play fp-visible\"><a class=\"fp-icon fp-playbtn\"><\/a><\/div><\/div>\n\n<\/div>\n\n              \n          <\/div>\n        <\/div>\n      <\/div>\n    \n    \n    <\/div><\/div>\t\t\t<script type=\"text\/javascript\">\r\n\t\t\t\tjQuery(document).ready(function ($) {\r\n\t\t\t\t\tif( typeof jQuery('.ult-carousel-2117653226a04642a442ce').slick == \"function\"){\r\n\t\t\t\t\t\t$('.ult-carousel-2117653226a04642a442ce').slick({dots: true,autoplaySpeed: 5000,speed: 500,infinite: false,arrows: true,nextArrow: '<button type=\"button\" role=\"button\" aria-label=\"Next\" style=\"color:#ffffff; font-size:30px;background:rgba(47,56,60,0.5);\" class=\"slick-next square-bg\"><i class=\"ultsl-arrow-right6\"><\/i><\/button>',prevArrow: '<button type=\"button\" role=\"button\" aria-label=\"Previous\" style=\"color:#ffffff; font-size:30px;background:rgba(47,56,60,0.5);\" class=\"slick-prev square-bg\"><i class=\"ultsl-arrow-left6\"><\/i><\/button>',slidesToScroll:1,slidesToShow:1,swipe: true,draggable: true,touchMove: true,pauseOnHover: true,pauseOnFocus: false,responsive: [\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t  breakpoint: 1026,\r\n\t\t\t\t\t\t\t  settings: {\r\n\t\t\t\t\t\t\t\tslidesToShow: 1,\r\n\t\t\t\t\t\t\t\tslidesToScroll: 1,  \r\n\t\t\t\t\t\t\t  }\r\n\t\t\t\t\t\t\t},\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t  breakpoint: 1025,\r\n\t\t\t\t\t\t\t  settings: {\r\n\t\t\t\t\t\t\t\tslidesToShow: 1,\r\n\t\t\t\t\t\t\t\tslidesToScroll: 1\r\n\t\t\t\t\t\t\t  }\r\n\t\t\t\t\t\t\t},\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t  breakpoint: 760,\r\n\t\t\t\t\t\t\t  settings: {\r\n\t\t\t\t\t\t\t\tslidesToShow: 1,\r\n\t\t\t\t\t\t\t\tslidesToScroll: 1\r\n\t\t\t\t\t\t\t  }\r\n\t\t\t\t\t\t\t}\r\n\t\t\t\t\t\t],pauseOnDotsHover: true,customPaging: function(slider, i) {\r\n                   return '<i type=\"button\" style= \"color:#788891;\" class=\"ultsl-record\" data-role=\"none\"><\/i>';\r\n                },});\r\n\t\t\t\t\t}\r\n\t\t\t\t});\r\n\t\t\t<\/script>\r\n\t\t\t\n  <\/div>\n  \n  \n  <\/div>\n[vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<h3>Desafios<\/h3>\n<ul class=\"ul-checkmarks\">\n<li>Redesenhar o sistema avan\u00e7ado de neurocirurgia<\/li>\n<li>Melhorar a interface do m\u00e9dico<\/li>\n<li>Transformar um projeto desatualizado com novos recursos<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<h3>Resultados<\/h3>\n<ul class=\"ul-checkmarks\">\n<li>Conjuga\u00e7\u00e3o dos esfor\u00e7os com especialistas em projeto e engenharia<\/li>\n<li>Percep\u00e7\u00e3o de que a antiga unidade era muito pesada e volumosa para transportar<\/li>\n<li>Utiliza\u00e7\u00e3o do Solid Edge como uma \u201clinguagem\u201d comum para o desenvolvimento<\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<p style=\"text-align: right;\"><a class=\"action-button transparent\" href=\"https:\/\/solidedge.siemens.com\/pt-br\/customer-story\/alpha-omega\/\"><i class=\"icon-ext\"><\/i>Leia a Hist\u00f3ria de Sucesso<\/a><\/p>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; el_class=&#8221;vc-row-customer-stories&#8221;][vc_column][vc_column_text el_class=&#8221;vc-el-lead-in&#8221;]Hist\u00f3rias de Clientes<\/p>\n<h2>Solid Edge e projeto de dispositivos m\u00e9dicos<\/h2>\n<p>[\/vc_column_text]\n\n\n<div id=\"wpv-view-layout-570-CATTRde946de4b3939c18485f4328c39fb86e\" class=\"js-wpv-view-layout js-wpv-layout-responsive js-wpv-view-layout-570-CATTRde946de4b3939c18485f4328c39fb86e\" data-viewnumber=\"570-CATTRde946de4b3939c18485f4328c39fb86e\" data-pagination=\"{&quot;id&quot;:570,&quot;query&quot;:&quot;normal&quot;,&quot;type&quot;:&quot;disabled&quot;,&quot;effect&quot;:&quot;fade&quot;,&quot;duration&quot;:500,&quot;speed&quot;:5,&quot;pause_on_hover&quot;:&quot;disabled&quot;,&quot;stop_rollover&quot;:&quot;false&quot;,&quot;cache_pages&quot;:&quot;enabled&quot;,&quot;preload_images&quot;:&quot;enabled&quot;,&quot;preload_pages&quot;:&quot;enabled&quot;,&quot;preload_reach&quot;:1,&quot;spinner&quot;:&quot;builtin&quot;,&quot;spinner_image&quot;:&quot;https:\/\/solidedge.siemens.com\/wp-content\/plugins\/wp-views\/embedded\/res\/img\/ajax-loader.gif&quot;,&quot;callback_next&quot;:&quot;&quot;,&quot;manage_history&quot;:&quot;disabled&quot;,&quot;has_controls_in_form&quot;:&quot;disabled&quot;,&quot;infinite_tolerance&quot;:&quot;0&quot;,&quot;max_pages&quot;:0,&quot;page&quot;:1,&quot;base_permalink&quot;:&quot;\/pt-br\/wp-json\/wp\/v2\/pages\/2305?wpv_view_count=570-CATTRde946de4b3939c18485f4328c39fb86e&amp;wpv_paged=WPV_PAGE_NUM&quot;,&quot;loop&quot;:{&quot;type&quot;:&quot;&quot;,&quot;name&quot;:&quot;&quot;,&quot;data&quot;:[],&quot;id&quot;:0}}\" data-permalink=\"\/pt-br\/wp-json\/wp\/v2\/pages\/2305?wpv_view_count=570-CATTRde946de4b3939c18485f4328c39fb86e\">\n\n\t\n    <div class=\"wpv-resources\">\n      <p class=\"see-more\"><a href=\"https:\/\/www.plm.automation.siemens.com\/global\/en\/our-story\/customers\/#\/?productKeywords=solidEdge\">See More Stories<\/a><\/p>\n      <div id=\"ult-carousel-19026330296a04642a4e6e0\" class=\"ult-carousel-wrapper  vc-el-carousel-customer-stories ult_horizontal\" data-gutter=\"0\" data-rtl=\"false\" ><div class=\"ult-carousel-14380525916a04642a4e6bd \" >\n      \n      \n        <div><!-- slide container -->\n          <div class=\"wpv-resources-item\" data-mh=\".wpv-resources-item\">\n            <div class=\"resources-item-poster\"><a href=\"https:\/\/solidedge.siemens.com\/pt-br\/customer-story\/diatron\/\" title=\"Read the Customer Story\"><img src=\"https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2018\/04\/c-diatron.jpg\" alt=\"Diatron\" class=\"attachment-resources-poster size-resources-poster wp-post-image\" \/><\/a>\n            <\/div>\n            <div class=\"resources-item-content\">\n              <p class=\"resources-item-meta\">Diatron | Hungary<\/p>\n              <p class=\"resources-item-title\">Diatron reduces time-to-market by 40 percent<\/p>\n              <p class=\"resources-item-read-more\"><a href=\"https:\/\/solidedge.siemens.com\/pt-br\/customer-story\/diatron\/\" title=\"Read the Customer Story\"><i class=\"icon-ext\"><\/i>Read the Customer Story<\/a><\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n      \n        <div><!-- slide container -->\n          <div class=\"wpv-resources-item\" data-mh=\".wpv-resources-item\">\n            <div class=\"resources-item-poster\"><a href=\"https:\/\/solidedge.siemens.com\/pt-br\/customer-story\/bhm-medical\/\" title=\"Read the Customer Story\"><img src=\"https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2018\/04\/c-bhm-medical.jpg\" alt=\"BHM Medical\" class=\"attachment-resources-poster size-resources-poster wp-post-image\" \/><\/a>\n            <\/div>\n            <div class=\"resources-item-content\">\n              <p class=\"resources-item-meta\">BHM Medical | Dispositivos M\u00e9dicos e Farmac\u00eauticas<\/p>\n              <p class=\"resources-item-title\">Engineering productivity supports aggressive growth<\/p>\n              <p class=\"resources-item-read-more\"><a href=\"https:\/\/solidedge.siemens.com\/pt-br\/customer-story\/bhm-medical\/\" title=\"Read the Customer Story\"><i class=\"icon-ext\"><\/i>Read the Customer Story<\/a><\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n      \n        <div><!-- slide container -->\n          <div class=\"wpv-resources-item\" data-mh=\".wpv-resources-item\">\n            <div class=\"resources-item-poster\"><a href=\"https:\/\/solidedge.siemens.com\/pt-br\/customer-story\/biotec\/\" title=\"Read the Customer Story\"><img src=\"https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2018\/04\/c-biotec.jpg\" alt=\"Biotec\" class=\"attachment-resources-poster size-resources-poster wp-post-image\" \/><\/a>\n            <\/div>\n            <div class=\"resources-item-content\">\n              <p class=\"resources-item-meta\">Biotec | Italy<\/p>\n              <p class=\"resources-item-title\">With Solid Edge and Femap, Biotec opens up new markets<\/p>\n              <p class=\"resources-item-read-more\"><a href=\"https:\/\/solidedge.siemens.com\/pt-br\/customer-story\/biotec\/\" title=\"Read the Customer Story\"><i class=\"icon-ext\"><\/i>Read the Customer Story<\/a><\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n      \n        <div><!-- slide container -->\n          <div class=\"wpv-resources-item\" data-mh=\".wpv-resources-item\">\n            <div class=\"resources-item-poster\"><a href=\"https:\/\/solidedge.siemens.com\/pt-br\/customer-story\/los-pinos\/\" title=\"Read the Customer Story\"><img src=\"https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2018\/04\/c-los-pinos.jpg\" alt=\"LOS PINOS\" class=\"attachment-resources-poster size-resources-poster wp-post-image\" \/><\/a>\n            <\/div>\n            <div class=\"resources-item-content\">\n              <p class=\"resources-item-meta\">LOS PINOS | Colombia<\/p>\n              <p class=\"resources-item-title\">3D design process facilitates ongoing product improvement<\/p>\n              <p class=\"resources-item-read-more\"><a href=\"https:\/\/solidedge.siemens.com\/pt-br\/customer-story\/los-pinos\/\" title=\"Read the Customer Story\"><i class=\"icon-ext\"><\/i>Read the Customer Story<\/a><\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n      \n      \n      <\/div><\/div>\t\t\t<script type=\"text\/javascript\">\r\n\t\t\t\tjQuery(document).ready(function ($) {\r\n\t\t\t\t\tif( typeof jQuery('.ult-carousel-14380525916a04642a4e6bd').slick == \"function\"){\r\n\t\t\t\t\t\t$('.ult-carousel-14380525916a04642a4e6bd').slick({dots: true,autoplaySpeed: 5000,speed: 500,infinite: false,arrows: true,nextArrow: '<button type=\"button\" role=\"button\" aria-label=\"Next\" style=\"color:#ffffff; font-size:30px;background:rgba(47,56,60,0.5);\" class=\"slick-next square-bg\"><i class=\"ultsl-arrow-right6\"><\/i><\/button>',prevArrow: '<button type=\"button\" role=\"button\" aria-label=\"Previous\" style=\"color:#ffffff; font-size:30px;background:rgba(47,56,60,0.5);\" class=\"slick-prev square-bg\"><i class=\"ultsl-arrow-left6\"><\/i><\/button>',slidesToScroll:3,slidesToShow:3,swipe: true,draggable: true,touchMove: true,pauseOnHover: true,pauseOnFocus: false,responsive: [\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t  breakpoint: 1026,\r\n\t\t\t\t\t\t\t  settings: {\r\n\t\t\t\t\t\t\t\tslidesToShow: 3,\r\n\t\t\t\t\t\t\t\tslidesToScroll: 3,  \r\n\t\t\t\t\t\t\t  }\r\n\t\t\t\t\t\t\t},\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t  breakpoint: 1025,\r\n\t\t\t\t\t\t\t  settings: {\r\n\t\t\t\t\t\t\t\tslidesToShow: 2,\r\n\t\t\t\t\t\t\t\tslidesToScroll: 2\r\n\t\t\t\t\t\t\t  }\r\n\t\t\t\t\t\t\t},\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t  breakpoint: 760,\r\n\t\t\t\t\t\t\t  settings: {\r\n\t\t\t\t\t\t\t\tslidesToShow: 1,\r\n\t\t\t\t\t\t\t\tslidesToScroll: 1\r\n\t\t\t\t\t\t\t  }\r\n\t\t\t\t\t\t\t}\r\n\t\t\t\t\t\t],pauseOnDotsHover: true,customPaging: function(slider, i) {\r\n                   return '<i type=\"button\" style= \"color:#788891;\" class=\"ultsl-record\" data-role=\"none\"><\/i>';\r\n                },});\r\n\t\t\t\t\t}\r\n\t\t\t\t});\r\n\t\t\t<\/script>\r\n\t\t\t\n\t<\/div>\n\t\n\t\n<\/div>\n[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; el_class=&#8221;vc-row-related-content&#8221; css=&#8221;.vc_custom_1524184785822{background-color: #347eb5 !important;}&#8221;][vc_column][vc_column_text]<\/p>\n<h2>Conte\u00fado relacionado<\/h2>\n<p>[\/vc_column_text]<div id=\"ult-carousel-20537887226a04642a4eb0f\" class=\"ult-carousel-wrapper  vc-el-carousel-related-content ult_horizontal\" data-gutter=\"0\" data-rtl=\"false\" ><div class=\"ult-carousel-21472476636a04642a4eaf2 \" >[vc_column_text]<a href=\"https:\/\/www.plm.automation.siemens.com\/store\/en-us\/solid-edge\/\">Adquira Solu\u00e7\u00f5es na loja do Solid Edge<\/a>[\/vc_column_text][vc_column_text]<a href=\"https:\/\/www.plm.automation.siemens.com\/en_us\/Images\/Siemens-PLM-Accelerate-Medical-Device-Design-With-Solid-Edge-sb_tcm1023-237262.pdf\">Insights da Ind\u00fastria:<br \/>\nAcelerar o Projeto de Dispositivos M\u00e9dicos com o Solid Edge<\/a>[\/vc_column_text][vc_column_text]<a href=\"https:\/\/solidedge.siemens.com\/pt-br\/solutions\/products\/complete-product-development-portfolio\/\">Saiba mais sobre o Portf\u00f3lio do Solid Edge<\/a>[\/vc_column_text]<div class=\"ult-item-wrap\" data-animation=\"animated no-animation\">[vc_column_text el_class=\"vc-el-related-content-video\"]<div class=\"ult-item-wrap\" data-animation=\"animated no-animation\"><\/div>[\/vc_column_text]<\/div><div class=\"ult-item-wrap\" data-animation=\"animated no-animation\">[vc_column_text el_class=\"vc-el-related-content-video\"]<div class=\"ult-item-wrap\" data-animation=\"animated no-animation\"><\/div>[\/vc_column_text]<\/div><\/div><\/div>\t\t\t<script type=\"text\/javascript\">\r\n\t\t\t\tjQuery(document).ready(function ($) {\r\n\t\t\t\t\tif( typeof jQuery('.ult-carousel-21472476636a04642a4eaf2').slick == \"function\"){\r\n\t\t\t\t\t\t$('.ult-carousel-21472476636a04642a4eaf2').slick({dots: true,autoplaySpeed: 5000,speed: 500,infinite: false,arrows: true,nextArrow: '<button type=\"button\" role=\"button\" aria-label=\"Next\" style=\"color:#ffffff; font-size:30px;background:rgba(255,255,255,0.2);\" class=\"slick-next square-bg\"><i class=\"ultsl-arrow-right6\"><\/i><\/button>',prevArrow: '<button type=\"button\" role=\"button\" aria-label=\"Previous\" style=\"color:#ffffff; font-size:30px;background:rgba(255,255,255,0.2);\" class=\"slick-prev square-bg\"><i class=\"ultsl-arrow-left6\"><\/i><\/button>',slidesToScroll:4,slidesToShow:4,swipe: true,draggable: true,touchMove: true,pauseOnHover: true,pauseOnFocus: false,responsive: [\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t  breakpoint: 1026,\r\n\t\t\t\t\t\t\t  settings: {\r\n\t\t\t\t\t\t\t\tslidesToShow: 4,\r\n\t\t\t\t\t\t\t\tslidesToScroll: 4,  \r\n\t\t\t\t\t\t\t  }\r\n\t\t\t\t\t\t\t},\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t  breakpoint: 1025,\r\n\t\t\t\t\t\t\t  settings: {\r\n\t\t\t\t\t\t\t\tslidesToShow: 2,\r\n\t\t\t\t\t\t\t\tslidesToScroll: 2\r\n\t\t\t\t\t\t\t  }\r\n\t\t\t\t\t\t\t},\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t  breakpoint: 760,\r\n\t\t\t\t\t\t\t  settings: {\r\n\t\t\t\t\t\t\t\tslidesToShow: 1,\r\n\t\t\t\t\t\t\t\tslidesToScroll: 1\r\n\t\t\t\t\t\t\t  }\r\n\t\t\t\t\t\t\t}\r\n\t\t\t\t\t\t],pauseOnDotsHover: true,customPaging: function(slider, i) {\r\n                   return '<i type=\"button\" style= \"color:#ffffff;\" class=\"ultsl-record\" data-role=\"none\"><\/i>';\r\n                },});\r\n\t\t\t\t\t}\r\n\t\t\t\t});\r\n\t\t\t<\/script>\r\n\t\t\t[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; el_class=&#8221;footer-contact&#8221; css=&#8221;.vc_custom_1550170708528{background-color: #dedee3 !important;}&#8221;][vc_column]<div class=\"wpb_content_block wpb_content_element\"><div class=\"wpb_wrapper\"><\/div><\/div>[\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p> Projeto de Dispositivos M\u00e9dicos Desenvolver dispositivos m\u00e9dicos inovadores e de alta qualidade com mais rapidez que a concorr\u00eancia Teste Gratuita do Solid Edge[\/vc_column_text][\/vc_column][\/vc_row][\/vc_column] Insights da Ind\u00fastria [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":2827,"menu_order":70,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.4.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Solid Edge para Dispositivos M\u00e9dicos | Software de Projeto<\/title>\n<meta name=\"description\" content=\"O Solid Edge fornece ferramentas de software profissionais e produtivas que ajudam a acelerar o projeto de dispositivos m\u00e9dicos para produzir equipamentos padronizados seguros e de alta qualidade\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/solidedge.siemens.com\/pt-br\/industries\/medical-devices\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Solid Edge para Dispositivos M\u00e9dicos | Software de Projeto\" \/>\n<meta property=\"og:description\" content=\"O Solid Edge fornece ferramentas de software profissionais e produtivas que ajudam a acelerar o projeto de dispositivos m\u00e9dicos para produzir equipamentos padronizados seguros e de alta qualidade\" \/>\n<meta property=\"og:url\" content=\"https:\/\/solidedge.siemens.com\/pt-br\/industries\/medical-devices\/\" \/>\n<meta property=\"og:site_name\" content=\"Solid Edge\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/solidedge\" \/>\n<meta property=\"article:modified_time\" content=\"2019-09-03T18:11:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@siemensplm\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/solidedge.siemens.com\/en\/#organization\",\"name\":\"Siemens Digital Industries Software\",\"url\":\"https:\/\/solidedge.siemens.com\/en\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/solidedge\",\"https:\/\/www.instagram.com\/siemens\/\",\"https:\/\/www.linkedin.com\/company\/siemens-plm-software\",\"https:\/\/www.youtube.com\/user\/PolarionSoftware\",\"https:\/\/twitter.com\/siemensplm\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/solidedge.siemens.com\/en\/#logo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2018\/04\/logo-siemens-ifl@2x.png\",\"contentUrl\":\"https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2018\/04\/logo-siemens-ifl@2x.png\",\"width\":640,\"height\":270,\"caption\":\"Siemens Digital Industries Software\"},\"image\":{\"@id\":\"https:\/\/solidedge.siemens.com\/en\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/solidedge.siemens.com\/en\/#website\",\"url\":\"https:\/\/solidedge.siemens.com\/en\/\",\"name\":\"Solid Edge\",\"description\":\"Siemens Software\",\"publisher\":{\"@id\":\"https:\/\/solidedge.siemens.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/solidedge.siemens.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/solidedge.siemens.com\/pt-br\/industries\/medical-devices\/#webpage\",\"url\":\"https:\/\/solidedge.siemens.com\/pt-br\/industries\/medical-devices\/\",\"name\":\"Solid Edge para Dispositivos M\u00e9dicos | Software de Projeto\",\"isPartOf\":{\"@id\":\"https:\/\/solidedge.siemens.com\/en\/#website\"},\"datePublished\":\"2018-03-30T19:06:08+00:00\",\"dateModified\":\"2019-09-03T18:11:45+00:00\",\"description\":\"O Solid Edge fornece ferramentas de software profissionais e produtivas que ajudam a acelerar o projeto de dispositivos m\u00e9dicos para produzir equipamentos padronizados seguros e de alta qualidade\",\"breadcrumb\":{\"@id\":\"https:\/\/solidedge.siemens.com\/pt-br\/industries\/medical-devices\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/solidedge.siemens.com\/pt-br\/industries\/medical-devices\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/solidedge.siemens.com\/pt-br\/industries\/medical-devices\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/solidedge.siemens.com\/en\/home-11\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Setores\",\"item\":\"https:\/\/solidedge.siemens.com\/pt-br\/industries\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dispositivos m\u00e9dicos\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Solid Edge para Dispositivos M\u00e9dicos | Software de Projeto","description":"O Solid Edge fornece ferramentas de software profissionais e produtivas que ajudam a acelerar o projeto de dispositivos m\u00e9dicos para produzir equipamentos padronizados seguros e de alta qualidade","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/solidedge.siemens.com\/pt-br\/industries\/medical-devices\/","og_locale":"pt_BR","og_type":"article","og_title":"Solid Edge para Dispositivos M\u00e9dicos | Software de Projeto","og_description":"O Solid Edge fornece ferramentas de software profissionais e produtivas que ajudam a acelerar o projeto de dispositivos m\u00e9dicos para produzir equipamentos padronizados seguros e de alta qualidade","og_url":"https:\/\/solidedge.siemens.com\/pt-br\/industries\/medical-devices\/","og_site_name":"Solid Edge","article_publisher":"https:\/\/www.facebook.com\/solidedge","article_modified_time":"2019-09-03T18:11:45+00:00","twitter_card":"summary_large_image","twitter_site":"@siemensplm","twitter_misc":{"Est. tempo de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/solidedge.siemens.com\/en\/#organization","name":"Siemens Digital Industries Software","url":"https:\/\/solidedge.siemens.com\/en\/","sameAs":["https:\/\/www.facebook.com\/solidedge","https:\/\/www.instagram.com\/siemens\/","https:\/\/www.linkedin.com\/company\/siemens-plm-software","https:\/\/www.youtube.com\/user\/PolarionSoftware","https:\/\/twitter.com\/siemensplm"],"logo":{"@type":"ImageObject","@id":"https:\/\/solidedge.siemens.com\/en\/#logo","inLanguage":"pt-BR","url":"https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2018\/04\/logo-siemens-ifl@2x.png","contentUrl":"https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2018\/04\/logo-siemens-ifl@2x.png","width":640,"height":270,"caption":"Siemens Digital Industries Software"},"image":{"@id":"https:\/\/solidedge.siemens.com\/en\/#logo"}},{"@type":"WebSite","@id":"https:\/\/solidedge.siemens.com\/en\/#website","url":"https:\/\/solidedge.siemens.com\/en\/","name":"Solid Edge","description":"Siemens Software","publisher":{"@id":"https:\/\/solidedge.siemens.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/solidedge.siemens.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/solidedge.siemens.com\/pt-br\/industries\/medical-devices\/#webpage","url":"https:\/\/solidedge.siemens.com\/pt-br\/industries\/medical-devices\/","name":"Solid Edge para Dispositivos M\u00e9dicos | Software de Projeto","isPartOf":{"@id":"https:\/\/solidedge.siemens.com\/en\/#website"},"datePublished":"2018-03-30T19:06:08+00:00","dateModified":"2019-09-03T18:11:45+00:00","description":"O Solid Edge fornece ferramentas de software profissionais e produtivas que ajudam a acelerar o projeto de dispositivos m\u00e9dicos para produzir equipamentos padronizados seguros e de alta qualidade","breadcrumb":{"@id":"https:\/\/solidedge.siemens.com\/pt-br\/industries\/medical-devices\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/solidedge.siemens.com\/pt-br\/industries\/medical-devices\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/solidedge.siemens.com\/pt-br\/industries\/medical-devices\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/solidedge.siemens.com\/en\/home-11\/"},{"@type":"ListItem","position":2,"name":"Setores","item":"https:\/\/solidedge.siemens.com\/pt-br\/industries\/"},{"@type":"ListItem","position":3,"name":"Dispositivos m\u00e9dicos"}]}]}},"_links":{"self":[{"href":"https:\/\/solidedge.siemens.com\/pt-br\/wp-json\/wp\/v2\/pages\/2305"}],"collection":[{"href":"https:\/\/solidedge.siemens.com\/pt-br\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/solidedge.siemens.com\/pt-br\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/solidedge.siemens.com\/pt-br\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/solidedge.siemens.com\/pt-br\/wp-json\/wp\/v2\/comments?post=2305"}],"version-history":[{"count":0,"href":"https:\/\/solidedge.siemens.com\/pt-br\/wp-json\/wp\/v2\/pages\/2305\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/solidedge.siemens.com\/pt-br\/wp-json\/wp\/v2\/pages\/2827"}],"wp:attachment":[{"href":"https:\/\/solidedge.siemens.com\/pt-br\/wp-json\/wp\/v2\/media?parent=2305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}