{"id":2061,"date":"2022-10-12T09:00:22","date_gmt":"2022-10-12T13:00:22","guid":{"rendered":"https:\/\/solidedge.siemens.com\/sheet-metal-design\/"},"modified":"2026-05-26T13:01:02","modified_gmt":"2026-05-26T17:01:02","slug":"sheet-metal-design","status":"publish","type":"page","link":"https:\/\/solidedge.siemens.com\/ja\/solutions\/products\/3d-design\/sheet-metal-design\/","title":{"rendered":"\u677f\u91d1\u8a2d\u8a08"},"content":{"rendered":"<p>[vc_row full_width=&#8221;stretch_row&#8221; full_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; css=&#8221;.vc_custom_1701462228099{background: #a6a6a6 url(https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2020\/05\/Improve-your-sheet-metal-design.jpg?id=23376) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221; el_class=&#8221;vc-row-hero-banner&#8221;][vc_column][vc_column_text el_class=&#8221;.vc-el-callout&#8221;]<\/p>\n<h1>Sheet metal design in Designcenter Solid Edge<\/h1>\n<p>Create 3D models, generate flat patterns, and perform simulation and analysis for sheet metal products such as enclosures, cabinets, brackets, panels, and other parts with sheet metal design capabilities in Designcenter Solid Edge. Easily create designs and concepts that meet your requirements, and validate designs at all stages, ensuring that products meet your standards for strength, rigidity, and durability.<\/p>\n<p><a class=\"action-button\" href=\"https:\/\/solidedge.siemens.com\/en\/try-now\/\"><i class=\"icon-ext\"><\/i>Start a 30-day free trial<\/a>[\/vc_column_text][\/vc_column][\/vc_row][vc_row disable_element=&#8221;yes&#8221; el_class=&#8221;vc-row-page-image-intro&#8221;][vc_column][vc_column_text]<\/p>\n<h2>\u677f\u91d1\u8a2d\u8a08<\/h2>\n<p>[\/vc_column_text][vc_row_inner][vc_column_inner width=&#8221;5\/12&#8243;][vc_single_image image=&#8221;62629&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;7\/12&#8243;][vc_column_text]<\/p>\n<p class=\"f-larger c-black\"><strong>Sheet metal design in Solid Edge: Complete, automated design with purpose-built tools<\/strong><\/p>\n<p>To meet unique sheet metal design challenges, like manufacturability, Solid Edge streamlines the entire sheet metal product development process, from CAD design through flat pattern and drawing development. Unlike general purpose CAD tools, Solid Edge includes sheet metal-specific features, like Emboss, Dimple, Drawn Cutout, Bead, Multi-edge Flange, Contour Flange, Straight Brake and Etch. And with integrated applications for analysis, NC programming, and related tasks, Solid Edge helps you speed design time, improve quality, and reduce costs.[\/vc_column_text][vc_column_text]<\/p>\n<p style=\"text-align: right;\"><a class=\"action-button\" href=\"\/en\/try-now\/\"><i class=\"icon-ext\"><\/i>Solid Edge Free Trial<\/a><\/p>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row el_class=&#8221;vc-row-accordion&#8221;][vc_column][vc_column_text]Capabilities<\/p>\n<h2>Complete, automated sheet metal design with purpose-built tools<\/h2>\n<p>To meet unique sheet metal design challenges, such as manufacturability, Designcenter Solid Edge streamlines the entire sheet metal product development process, from CAD design through flat pattern and drawing development.<\/p>\n<p>Unlike general purpose CAD tools, Solid Edge includes sheet metal-specific features, such as Emboss, Dimple, Drawn Cutout, Bead, Multi-Edge Flange, Contour Flange, Straight Brake, and Etch. And with integrated applications for analysis, NC programming, and related tasks, Designcenter Solid Edge helps you speed design time, improve quality, and reduce costs.[\/vc_column_text][vc_tta_accordion style=&#8221;flat&#8221; shape=&#8221;square&#8221; active_section=&#8221;0&#8243; no_fill=&#8221;true&#8221; collapsible_all=&#8221;true&#8221; el_class=&#8221;vc-el-accordion&#8221;][vc_tta_section title=&#8221;Develop sheet metal models with fewer steps&#8221; tab_id=&#8221;ui_Develop_Sheet_Metal_Models_with_Fewer_Steps&#8221;][vc_row_inner][vc_column_inner width=&#8221;7\/12&#8243;][vc_column_text]<\/p>\n<h2>Develop sheet metal models with fewer steps<\/h2>\n<p>Effortlessly create sheet metal models from 2D sketches and work directly with geometry. With synchronous technology in Designcenter Solid Edge, unlike in history-based CAD, features can be edited independently. You can reorder, reorganize, and sort them by name or type. Specialized sheet metal design capabilities allow you to create and make edits to sheet metal features, such as dimples and beads, using sketches and engineering parameters, without having to regenerate unrelated geometry or downstream operations. Multiple flanges can be created in a single operation and flanges can be automatically trimmed. In addition, Designcenter Solid Edge allows you to \u201cwrap\u201d sheet metal around a solid part.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;5\/12&#8243;][vc_single_image image=&#8221;799&#8243; img_size=&#8221;accordion-image&#8221; alignment=&#8221;center&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_tta_section][vc_tta_section title=&#8221;Easily make changes at all stages of design&#8221; tab_id=&#8221;ui_Easily_Make_Changes_at_All_Stages_of_Design&#8221;][vc_row_inner][vc_column_inner width=&#8221;7\/12&#8243;][vc_column_text]<\/p>\n<h2>Easily make changes at all stages of design<\/h2>\n<p>Easily make unplanned design changes to sheet metal models while maintaining design intent. Automatically find and maintain design intent, including geometric conditions and model parameters, during drags or dimensional edits. Add driving dimensions to any part of your 3D sheet metal model. Unlike traditional CAD systems, Designcenter Solid Edge with synchronous technology doesn\u2019t force edits down the tree in the order of creation, or the regeneration of unrelated features\u2014so you can edit the first operation as fast as the last.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;5\/12&#8243;][vc_single_image image=&#8221;798&#8243; img_size=&#8221;accordion-image&#8221; alignment=&#8221;center&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_tta_section][vc_tta_section title=&#8221;Seamlessly reuse supplier and legacy 3D designs&#8221; tab_id=&#8221;ui_Seamlessly_Reuse_Supplier_and_Legacy_3D_Designs&#8221;][vc_row_inner][vc_column_inner width=&#8221;7\/12&#8243;][vc_column_text]<\/p>\n<h2>Seamlessly reuse supplier and legacy 3D designs<\/h2>\n<p>Import sheet metal model files and convert them to usable parts where edits can then be made. Designcenter Solid Edge recognizes key parameters on imported parts, such as thickness and bends. With Designcenter Solid Edge, you can continue to design and make edits to imported parts as if they were native geometry\u2014by simply dragging features like tabs or flanges\u2014without remodeling.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;5\/12&#8243;][vc_single_image image=&#8221;802&#8243; img_size=&#8221;accordion-image&#8221; alignment=&#8221;center&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_tta_section][vc_tta_section title=&#8221;Save time with purpose-built capabilities&#8221; tab_id=&#8221;ui_Save_Time_with_Purpose-Built_Capabilities&#8221;][vc_row_inner][vc_column_inner width=&#8221;7\/12&#8243;][vc_column_text]<\/p>\n<h2>Save time with purpose-built capabilities<\/h2>\n<p>Specialized sheet metal design capabilities in Designcenter Solid Edge deliver significant productivity gains compared to general-purpose CAD tools. Process-specific commands\u2014like Lofted Flange for ducting, Part to Sheet Metal for hopper design, and Blank Body for press flat patterns\u2014allow you to model sheet metal parts more quickly. Built-in intelligence saves additional time by automatically calculating material treatments and validating parts for manufacturability. In addition, the ability to create manufacturing-ready sheet metal flat patterns helps eliminate scrap and rework.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;5\/12&#8243;][vc_single_image image=&#8221;399&#8243; img_size=&#8221;accordion-image&#8221; alignment=&#8221;center&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_tta_section][vc_tta_section title=&#8221;Improve quality with built-in design validation&#8221; tab_id=&#8221;ui_Improve_Quality_with_Built-in_Design_Validation&#8221;][vc_row_inner][vc_column_inner width=&#8221;7\/12&#8243;][vc_column_text]<\/p>\n<h2>Improve quality with built-in design validation<\/h2>\n<p>Designcenter Solid Edge provides unmatched model validation to ensure manufacturability and reduce the need for physical prototypes. Designcenter Solid Edge includes design sensors that can automatically measure parameters, like the distance between bends, or calculate factors such as cost, variables, and surface area. And with scalable finite element capabilities, you can conduct simulations earlier in the design phase, allowing you to improve the quality of sheet metal parts and reduce product failures, while minimizing material and weight.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;5\/12&#8243;][vc_single_image image=&#8221;797&#8243; img_size=&#8221;accordion-image&#8221; alignment=&#8221;center&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_tta_section][vc_tta_section title=&#8221;Quickly create accurate drawings&#8221; tab_id=&#8221;ui_Quickly_Create_Accurate_Drawings&#8221;][vc_row_inner][vc_column_inner width=&#8221;7\/12&#8243;][vc_column_text]<\/p>\n<h2>Quickly create accurate drawings<\/h2>\n<p>Designcenter Solid Edge streamlines sheet metal drawing creation, including bend tables, with the industry\u2019s most productive CAD drafting system. Formed and flattened components can be detailed, dimensioned, and associatively retained so that they automatically update when your designs change. Bend tables, shaded views, exploded assemblies, and detail and section views can be quickly created within the drawing. Using Microsoft-standard OLE technology (object link and embedding), whole drawings, bend tables, or individual views can be easily re-used in other document types, such as Word, Excel and PowerPoint, to illustrate manuals, technical specifications, brochures, and other publications.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;5\/12&#8243;][vc_single_image image=&#8221;801&#8243; img_size=&#8221;accordion-image&#8221; alignment=&#8221;center&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_tta_section][vc_tta_section title=&#8221;Create NC-ready flat patterns&#8221; tab_id=&#8221;ui_Create_NC-ready_Flat_Patterns&#8221;][vc_row_inner][vc_column_inner width=&#8221;7\/12&#8243;][vc_column_text]<\/p>\n<h2>Create NC-ready flat patterns<\/h2>\n<p>Designcenter Solid Edge uses an industry-standard formula to create an NC-ready flat pattern, but gives you the flexibility to define a custom formula based on bend tables. For manufacturing purposes, Designcenter Solid Edge flat patterns will always show the most efficient cut sheet size. Designcenter Solid Edge lets you represent deformation features in a manner that best suits your sheet metal manufacturing process. Bend tables can be stored within 3D parts to allow the bend order to be documented, used on drawings, and exported to help program CNC machines. Designcenter Solid Edge also allows the user to remove undesired reliefs from flat patterns and supports the use of triangulation lines for conical bends \u2013 an important enhancement for anyone who creates transitional sheet metal work like square to rounds or conical shapes.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;5\/12&#8243;][vc_single_image image=&#8221;800&#8243; img_size=&#8221;accordion-image&#8221; alignment=&#8221;center&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_tta_section][vc_tta_section title=&#8221;Use unique functions to easily build complex models&#8221; tab_id=&#8221;ui-use-unique-functions&#8221;][vc_row_inner][vc_column_inner width=&#8221;7\/12&#8243;][vc_column_text]<\/p>\n<h2>Use unique functions to easily build complex models<\/h2>\n<p>Build complex 3D sheet metal models more easily using enhanced lofted flanges and unique bend bulge relief in a 3D CAD environment. The lofted flange capability improves manufacturability and handles a multitude of cases: one-to-one, one-to-many, arc-to-line, symmetrical, asymmetrical, parallel and non-parallel. The unique auto-relief feature results in more successful creation of lofted flanges. And the new lofted flange bends option provides creation flexibility and accurate flat patterns. In addition, a new bend bulge relief function adds relief to simple bend ends. Lofted flanges are especially useful in the creation of agricultural machine design and industrial food processing equipment. Bend bulges, mechanical deformations that happen when metal plates are bent, can be relieved, a necessary step for manufacturing.<\/p>\n<p style=\"text-align: right;\"><a class=\"action-button\" href=\"\/en\/try-now\/\"><i class=\"icon-ext\"><\/i>Start a 30-day free trial<\/a><\/p>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;5\/12&#8243;][vc_single_image image=&#8221;17148&#8243; img_size=&#8221;accordion-image&#8221; alignment=&#8221;center&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_tta_section][\/vc_tta_accordion][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; el_class=&#8221;vc-row-free-software&#8221; css=&#8221;.vc_custom_1523912493378{background-color: #006486 !important;}&#8221;][vc_column][vc_column_text el_class=&#8221;vc-el-lead-in&#8221;]Offers<\/p>\n<h2>Free software for product development<\/h2>\n<p>[\/vc_column_text][vc_row_inner equal_height=&#8221;yes&#8221;][vc_column_inner width=&#8221;1\/2&#8243; offset=&#8221;vc_col-md-5&#8243;]<div class=\"wpb_content_block wpb_content_element\"><div class=\"wpb_wrapper\"><div class=\"content_block\" id=\"custom_post_widget-418\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<h3>Solid Edge\u306e\u7121\u511f\u8a55\u4fa1<\/h3>\n<p>Solid Edge\u7121\u511f\u8a55\u4fa1\u7248\u306b\u3059\u3050\u306b\u30a2\u30af\u30bb\u30b9\u3057\u3066\u3001\u3054\u81ea\u5206\u3067\u304a\u8a66\u3057\u304f\u3060\u3055\u3044\u3002[\/vc_column_text][vc_column_text]<a class=\"action-button\" href=\"\/ja\/try-now\/\"><i class=\"icon-ext\"><\/i>\u4eca\u3059\u3050\u30b9\u30bf\u30fc\u30c8<\/a>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div><\/div><\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243; offset=&#8221;vc_col-md-offset-2 vc_col-md-5&#8243;]<div class=\"wpb_content_block wpb_content_element\"><div class=\"wpb_wrapper\"><div class=\"content_block\" id=\"custom_post_widget-419\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<h3>\u30b9\u30bf\u30fc\u30c8\u30a2\u30c3\u30d7\u4f01\u696d\u3092\u652f\u63f4\u3059\u308b\u7121\u511f\u306e\u30bd\u30d5\u30c8\u30a6\u30a7\u30a2<\/h3>\n<p>\u4e8b\u696d\u306e\u7acb\u3061\u4e0a\u3052\u304b\u30893\u5e74\u4ee5\u5185\u306e\u30b9\u30bf\u30fc\u30c8\u30a2\u30c3\u30d7\u4f01\u696d\u3067\u3042\u308c\u3070\u3001Solid Edge\u3092\u7121\u511f\u3067\u3054\u5229\u7528\u3044\u305f\u3060\u3051\u307e\u3059\u3002 \u7533\u8fbc\u91d1\u306f\u4e0d\u8981\u3067\u3059\u3002[\/vc_column_text][vc_column_text]<a class=\"action-button\" href=\"https:\/\/www.plm.automation.siemens.com\/global\/en\/topic\/solid-edge-for-startups\/8335\"><i class=\"icon-ext\"><\/i>\u4eca\u3059\u3050\u304a\u7533\u8fbc\u307f\u304f\u3060\u3055\u3044\u3002<\/a>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div><\/div><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1524332180484{background-color: #ffffff !important;}&#8221; el_class=&#8221;vc-row-video-highlight&#8221;][vc_column][vc_column_text el_class=&#8221;vc-el-lead-in&#8221;]Video<\/p>\n<h2>See Designcenter Solid Edge in action<\/h2>\n<p>A core design capability of Designcenter Solid Edge is the sheet metal environment, which provides an entire design-through-fabrication workflow, using streamlined synchronous modeling methods tailored to your unique needs.<\/p>\n<p class=\"see-more\" style=\"text-align: right;\"><a href=\"#see-more-videos\">See more videos<\/a><\/p>\n<p>[\/vc_column_text]\n\n\n  <div id=\"wpv-view-layout-567-CATTRd1699b0972a1e98f4381f337aab89d1a\" class=\"js-wpv-view-layout js-wpv-layout-responsive js-wpv-view-layout-567-CATTRd1699b0972a1e98f4381f337aab89d1a\" data-viewnumber=\"567-CATTRd1699b0972a1e98f4381f337aab89d1a\" data-pagination=\"{&quot;id&quot;:567,&quot;query&quot;:&quot;normal&quot;,&quot;type&quot;:&quot;disabled&quot;,&quot;effect&quot;:&quot;fade&quot;,&quot;duration&quot;:500,&quot;speed&quot;:5,&quot;pause_on_hover&quot;:&quot;disabled&quot;,&quot;stop_rollover&quot;:&quot;false&quot;,&quot;cache_pages&quot;:&quot;enabled&quot;,&quot;preload_images&quot;:&quot;enabled&quot;,&quot;preload_pages&quot;:&quot;enabled&quot;,&quot;preload_reach&quot;:1,&quot;spinner&quot;:&quot;builtin&quot;,&quot;spinner_image&quot;:&quot;https:\/\/solidedge.siemens.com\/wp-content\/plugins\/wp-views\/embedded\/res\/img\/ajax-loader.gif&quot;,&quot;callback_next&quot;:&quot;&quot;,&quot;manage_history&quot;:&quot;disabled&quot;,&quot;has_controls_in_form&quot;:&quot;disabled&quot;,&quot;infinite_tolerance&quot;:&quot;0&quot;,&quot;max_pages&quot;:0,&quot;page&quot;:1,&quot;base_permalink&quot;:&quot;\/ja\/wp-json\/wp\/v2\/pages\/2061?wpv_view_count=567-CATTRd1699b0972a1e98f4381f337aab89d1a&amp;wpv_paged=WPV_PAGE_NUM&quot;,&quot;loop&quot;:{&quot;type&quot;:&quot;&quot;,&quot;name&quot;:&quot;&quot;,&quot;data&quot;:[],&quot;id&quot;:0}}\" data-permalink=\"\/ja\/wp-json\/wp\/v2\/pages\/2061?wpv_view_count=567-CATTRd1699b0972a1e98f4381f337aab89d1a\">\n\n  \n  <div class=\"wpv-resources\"><a name=\"video\" class=\"video-anchor\"><\/a>\n    <div id=\"ult-carousel-19097365596a977d8ec7938\" class=\"ult-carousel-wrapper  vc-el-carousel-videos-embedded ult_horizontal\" data-gutter=\"0\" data-rtl=\"false\" ><div class=\"ult-carousel-19353215896a977d8ec7912 \" >\n    \n    \n       <div><!-- slide container -->\n        <div class=\"wpv-resources-item\" data-mh=\".wpv-resources-item\">\n          <div class=\"resources-item-poster\">\n              <div id=\"wpfp_b94c7d239167a843290ff077e9e8b081\" data-item=\"{&quot;sources&quot;:&#091;{&quot;src&quot;:&quot;https:\\\/\\\/media.plm.automation.siemens.com\\\/solidedge\\\/Sheet-Metal-Enclosures.mp4&quot;,&quot;type&quot;:&quot;video\\\/mp4&quot;}&#093;}\" class=\"flowplayer no-brand is-splash no-svg is-paused skin-slim fp-slim fp-edgy\" data-embed=\"false\" style=\"max-width: 1140px; max-height: 640px; background-image: url(https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2018\/04\/v-enclosure-design.jpg);\" data-ratio=\"0.5614\" data-advance=\"false\">\n\t<div class=\"fp-ratio\" style=\"padding-top: 56.14%\"><\/div>\n\t<div class=\"fp-ui\"><div class=\"fp-play fp-visible\"><a class=\"fp-icon fp-playbtn\"><\/a><\/div><\/div>\n\n<\/div>\n\n              <div class=\"resources-caption\">\u30b7\u30fc\u30c8\u30e1\u30bf\u30eb\u3000\u30a8\u30f3\u30af\u30ed\u30fc\u30b8\u30e3\u8a2d\u8a08<\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n    \n       <div><!-- slide container -->\n        <div class=\"wpv-resources-item\" data-mh=\".wpv-resources-item\">\n          <div class=\"resources-item-poster\">\n              <div id=\"wpfp_208fe65585d19d1af19d91653d15315c\" data-item=\"{&quot;sources&quot;:&#091;{&quot;src&quot;:&quot;https:\\\/\\\/media.plm.automation.siemens.com\\\/solidedge\\\/Sheet-Metal-Straight-Brake.mp4&quot;,&quot;type&quot;:&quot;video\\\/mp4&quot;}&#093;}\" class=\"flowplayer no-brand is-splash no-svg is-paused skin-slim fp-slim fp-edgy\" data-embed=\"false\" style=\"max-width: 1140px; max-height: 640px; background-image: url(https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2018\/04\/v-straight-break2.jpg);\" data-ratio=\"0.5614\" data-advance=\"false\">\n\t<div class=\"fp-ratio\" style=\"padding-top: 56.14%\"><\/div>\n\t<div class=\"fp-ui\"><div class=\"fp-play fp-visible\"><a class=\"fp-icon fp-playbtn\"><\/a><\/div><\/div>\n\n<\/div>\n\n              <div class=\"resources-caption\">\u30b7\u30fc\u30c8\u30e1\u30bf\u30eb\u3000\u30b9\u30c8\u30ec\u30fc\u30c8\u30fb\u30d6\u30ec\u30fc\u30ad<\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n    \n       <div><!-- slide container -->\n        <div class=\"wpv-resources-item\" data-mh=\".wpv-resources-item\">\n          <div class=\"resources-item-poster\">\n              <div id=\"wpfp_11969fc97b31bcda8c85a955c9d3a0fd\" data-item=\"{&quot;sources&quot;:&#091;{&quot;src&quot;:&quot;https:\\\/\\\/media.plm.automation.siemens.com\\\/solidedge\\\/Rapid-Initial-Design-Vignette.mp4&quot;,&quot;type&quot;:&quot;video\\\/mp4&quot;}&#093;}\" class=\"flowplayer no-brand is-splash no-svg is-paused skin-slim fp-slim fp-edgy\" data-embed=\"false\" style=\"max-width: 1140px; max-height: 640px; background-image: url(https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2018\/04\/v-rapid-initial-design2.jpg);\" data-ratio=\"0.5614\" data-advance=\"false\">\n\t<div class=\"fp-ratio\" style=\"padding-top: 56.14%\"><\/div>\n\t<div class=\"fp-ui\"><div class=\"fp-play fp-visible\"><a class=\"fp-icon fp-playbtn\"><\/a><\/div><\/div>\n\n<\/div>\n\n              <div class=\"resources-caption\">\u8fc5\u901f\u306a\u521d\u671f\u8a2d\u8a08<\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n    \n    \n    <\/div><\/div>\t\t\t<script type=\"text\/javascript\">\r\n\t\t\t\tjQuery(document).ready(function ($) {\r\n\t\t\t\t\tif( typeof jQuery('.ult-carousel-19353215896a977d8ec7912').slick == \"function\"){\r\n\t\t\t\t\t\t$('.ult-carousel-19353215896a977d8ec7912').slick({dots: true,autoplaySpeed: 5000,speed: 500,infinite: false,arrows: true,nextArrow: '<button type=\"button\" role=\"button\" aria-label=\"Next\" style=\"color:#ffffff; font-size:30px;background:rgba(47,56,60,0.5);\" class=\"slick-next square-bg\"><i class=\"ultsl-arrow-right6\"><\/i><\/button>',prevArrow: '<button type=\"button\" role=\"button\" aria-label=\"Previous\" style=\"color:#ffffff; font-size:30px;background:rgba(47,56,60,0.5);\" class=\"slick-prev square-bg\"><i class=\"ultsl-arrow-left6\"><\/i><\/button>',slidesToScroll:1,slidesToShow:1,swipe: true,draggable: true,touchMove: true,pauseOnHover: true,pauseOnFocus: false,responsive: [\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t  breakpoint: 1026,\r\n\t\t\t\t\t\t\t  settings: {\r\n\t\t\t\t\t\t\t\tslidesToShow: 1,\r\n\t\t\t\t\t\t\t\tslidesToScroll: 1,  \r\n\t\t\t\t\t\t\t  }\r\n\t\t\t\t\t\t\t},\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t  breakpoint: 1025,\r\n\t\t\t\t\t\t\t  settings: {\r\n\t\t\t\t\t\t\t\tslidesToShow: 1,\r\n\t\t\t\t\t\t\t\tslidesToScroll: 1\r\n\t\t\t\t\t\t\t  }\r\n\t\t\t\t\t\t\t},\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t  breakpoint: 760,\r\n\t\t\t\t\t\t\t  settings: {\r\n\t\t\t\t\t\t\t\tslidesToShow: 1,\r\n\t\t\t\t\t\t\t\tslidesToScroll: 1\r\n\t\t\t\t\t\t\t  }\r\n\t\t\t\t\t\t\t}\r\n\t\t\t\t\t\t],pauseOnDotsHover: true,customPaging: function(slider, i) {\r\n                   return '<i type=\"button\" style= \"color:#788891;\" class=\"ultsl-record\" data-role=\"none\"><\/i>';\r\n                },});\r\n\t\t\t\t\t}\r\n\t\t\t\t});\r\n\t\t\t<\/script>\r\n\t\t\t\n  <\/div>\n  \n  \n  <\/div>\n[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1523655515924{background-color: #f0f2f4 !important;}&#8221;][vc_column][vc_column_text el_class=&#8221;vc-el-lead-in&#8221;]Customer Stories<\/p>\n<h2>How real companies are seeing the benefits of sheet metal design in Designcenter Solid Edge<\/h2>\n<p>[\/vc_column_text]\n\n\n<div id=\"wpv-view-layout-570-CATTR8ee57dabdb1cc6e9836df2b574bb5c9c\" class=\"js-wpv-view-layout js-wpv-layout-responsive js-wpv-view-layout-570-CATTR8ee57dabdb1cc6e9836df2b574bb5c9c\" data-viewnumber=\"570-CATTR8ee57dabdb1cc6e9836df2b574bb5c9c\" data-pagination=\"{&quot;id&quot;:570,&quot;query&quot;:&quot;normal&quot;,&quot;type&quot;:&quot;disabled&quot;,&quot;effect&quot;:&quot;fade&quot;,&quot;duration&quot;:500,&quot;speed&quot;:5,&quot;pause_on_hover&quot;:&quot;disabled&quot;,&quot;stop_rollover&quot;:&quot;false&quot;,&quot;cache_pages&quot;:&quot;enabled&quot;,&quot;preload_images&quot;:&quot;enabled&quot;,&quot;preload_pages&quot;:&quot;enabled&quot;,&quot;preload_reach&quot;:1,&quot;spinner&quot;:&quot;builtin&quot;,&quot;spinner_image&quot;:&quot;https:\/\/solidedge.siemens.com\/wp-content\/plugins\/wp-views\/embedded\/res\/img\/ajax-loader.gif&quot;,&quot;callback_next&quot;:&quot;&quot;,&quot;manage_history&quot;:&quot;disabled&quot;,&quot;has_controls_in_form&quot;:&quot;disabled&quot;,&quot;infinite_tolerance&quot;:&quot;0&quot;,&quot;max_pages&quot;:0,&quot;page&quot;:1,&quot;base_permalink&quot;:&quot;\/ja\/wp-json\/wp\/v2\/pages\/2061?wpv_view_count=570-CATTR8ee57dabdb1cc6e9836df2b574bb5c9c&amp;wpv_paged=WPV_PAGE_NUM&quot;,&quot;loop&quot;:{&quot;type&quot;:&quot;&quot;,&quot;name&quot;:&quot;&quot;,&quot;data&quot;:[],&quot;id&quot;:0}}\" data-permalink=\"\/ja\/wp-json\/wp\/v2\/pages\/2061?wpv_view_count=570-CATTR8ee57dabdb1cc6e9836df2b574bb5c9c\">\n\n\t\n    <div class=\"wpv-resources\">\n      <p class=\"see-more\"><a href=\"https:\/\/www.plm.automation.siemens.com\/global\/en\/our-story\/customers\/#\/?productKeywords=solidEdge\">See More Stories<\/a><\/p>\n      <div id=\"ult-carousel-3902225266a977d8f14007\" class=\"ult-carousel-wrapper  vc-el-carousel-customer-stories ult_horizontal\" data-gutter=\"0\" data-rtl=\"false\" ><div class=\"ult-carousel-3330854776a977d8f13fe4 \" >\n      \n      \n        <div><!-- slide container -->\n          <div class=\"wpv-resources-item\" data-mh=\".wpv-resources-item\">\n            <div class=\"resources-item-poster\"><a href=\"https:\/\/solidedge.siemens.com\/ja\/customer-story\/red-ant-agri-engineering\/\" title=\"Read the Customer Story\"><img src=\"https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2022\/05\/red-ant-agri-engineering-84274-hero-1280x720-1.jpg\" class=\"attachment-resources-poster size-resources-poster wp-post-image\" \/><\/a>\n            <\/div>\n            <div class=\"resources-item-content\">\n              <p class=\"resources-item-meta\">Red Ant Agri Engineering | \u5357\u30a2\u30d5\u30ea\u30ab<\/p>\n              <p class=\"resources-item-title\">\u30c7\u30b8\u30bf\u30eb\u30fb\u30d7\u30ed\u30c8\u30bf\u30a4\u30d7\u306e\u6d3b\u7528\u3067\u58f2\u4e0a\u3092500%\u5897\u52a0<\/p>\n              <p class=\"resources-item-read-more\"><a href=\"https:\/\/solidedge.siemens.com\/ja\/customer-story\/red-ant-agri-engineering\/\" title=\"Read the Customer Story\"><i class=\"icon-ext\"><\/i>Read the Customer Story<\/a><\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n      \n        <div><!-- slide container -->\n          <div class=\"wpv-resources-item\" data-mh=\".wpv-resources-item\">\n            <div class=\"resources-item-poster\"><a href=\"https:\/\/solidedge.siemens.com\/ja\/customer-story\/sanneng\/\" title=\"Read the Customer Story\"><img src=\"https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2019\/05\/sanneng-1280x720-480x270.jpg\" alt=\"Sanneng\" class=\"attachment-resources-poster size-resources-poster wp-post-image\" \/><\/a>\n            <\/div>\n            <div class=\"resources-item-content\">\n              <p class=\"resources-item-meta\">Sanneng | Taiwan<\/p>\n              <p class=\"resources-item-title\">Baking equipment manufacturer uses Solid Edge to simplify product design<\/p>\n              <p class=\"resources-item-read-more\"><a href=\"https:\/\/solidedge.siemens.com\/ja\/customer-story\/sanneng\/\" title=\"Read the Customer Story\"><i class=\"icon-ext\"><\/i>Read the Customer Story<\/a><\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n      \n        <div><!-- slide container -->\n          <div class=\"wpv-resources-item\" data-mh=\".wpv-resources-item\">\n            <div class=\"resources-item-poster\"><a href=\"https:\/\/solidedge.siemens.com\/ja\/customer-story\/sparkonix\/\" title=\"Read the Customer Story\"><img src=\"https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2018\/04\/c-sparkonix.jpg\" alt=\"Sparkonix (Teamcenter Rapid Start)\" class=\"attachment-resources-poster size-resources-poster wp-post-image\" \/><\/a>\n            <\/div>\n            <div class=\"resources-item-content\">\n              <p class=\"resources-item-meta\">Sparkonix | India<\/p>\n              <p class=\"resources-item-title\">Teamcenter Rapid Start to reduce design time by 25%<\/p>\n              <p class=\"resources-item-read-more\"><a href=\"https:\/\/solidedge.siemens.com\/ja\/customer-story\/sparkonix\/\" title=\"Read the Customer Story\"><i class=\"icon-ext\"><\/i>Read the Customer Story<\/a><\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n      \n        <div><!-- slide container -->\n          <div class=\"wpv-resources-item\" data-mh=\".wpv-resources-item\">\n            <div class=\"resources-item-poster\"><a href=\"https:\/\/solidedge.siemens.com\/ja\/customer-story\/kaspar-schulz\/\" title=\"Read the Customer Story\"><img src=\"https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2018\/04\/c-kaspar-schulz.jpg\" alt=\"Kaspar Schulz\" class=\"attachment-resources-poster size-resources-poster wp-post-image\" \/><\/a>\n            <\/div>\n            <div class=\"resources-item-content\">\n              <p class=\"resources-item-meta\">Kaspar Schulz | Germany<\/p>\n              <p class=\"resources-item-title\">Integration of project planning, pipe routing and 3D design<\/p>\n              <p class=\"resources-item-read-more\"><a href=\"https:\/\/solidedge.siemens.com\/ja\/customer-story\/kaspar-schulz\/\" title=\"Read the Customer Story\"><i class=\"icon-ext\"><\/i>Read the Customer Story<\/a><\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n      \n        <div><!-- slide container -->\n          <div class=\"wpv-resources-item\" data-mh=\".wpv-resources-item\">\n            <div class=\"resources-item-poster\"><a href=\"https:\/\/solidedge.siemens.com\/ja\/customer-story\/theebo-tech-design-speed\/\" title=\"Read the Customer Story\"><img src=\"https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2018\/04\/v-theebo-480x270.jpg\" alt=\"Theebo Tech\" class=\"attachment-resources-poster size-resources-poster wp-post-image\" \/><\/a>\n            <\/div>\n            <div class=\"resources-item-content\">\n              <p class=\"resources-item-meta\">Theebo Tech | South Africa<\/p>\n              <p class=\"resources-item-title\">Agricultural equipment manufacturer speeds up product design with Solid Edge<\/p>\n              <p class=\"resources-item-read-more\"><a href=\"https:\/\/solidedge.siemens.com\/ja\/customer-story\/theebo-tech-design-speed\/\" title=\"Read the Customer Story\"><i class=\"icon-ext\"><\/i>Read the Customer Story<\/a><\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n      \n        <div><!-- slide container -->\n          <div class=\"wpv-resources-item\" data-mh=\".wpv-resources-item\">\n            <div class=\"resources-item-poster\"><a href=\"https:\/\/solidedge.siemens.com\/ja\/customer-story\/delaval\/\" title=\"Read the Customer Story\"><img src=\"https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2018\/04\/c-delaval.jpg\" alt=\"DeLaval\" class=\"attachment-resources-poster size-resources-poster wp-post-image\" \/><\/a>\n            <\/div>\n            <div class=\"resources-item-content\">\n              <p class=\"resources-item-meta\">DeLaval | Sweden<\/p>\n              <p class=\"resources-item-title\">Dairy equipment manufacturer creates smart products for smart farmers<\/p>\n              <p class=\"resources-item-read-more\"><a href=\"https:\/\/solidedge.siemens.com\/ja\/customer-story\/delaval\/\" title=\"Read the Customer Story\"><i class=\"icon-ext\"><\/i>Read the Customer Story<\/a><\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n      \n        <div><!-- slide container -->\n          <div class=\"wpv-resources-item\" data-mh=\".wpv-resources-item\">\n            <div class=\"resources-item-poster\"><a href=\"https:\/\/solidedge.siemens.com\/ja\/customer-story\/gif-module\/\" title=\"Read the Customer Story\"><img src=\"https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2019\/04\/customer-story-gifmodule-480x270.jpg\" class=\"attachment-resources-poster size-resources-poster wp-post-image\" \/><\/a>\n            <\/div>\n            <div class=\"resources-item-content\">\n              <p class=\"resources-item-meta\">GIF MODUL | Asz\u00f3d, Hungary | Automotive & Transportation<\/p>\n              <p class=\"resources-item-title\">Accelerated, more efficient design and construction with Solid Edge<\/p>\n              <p class=\"resources-item-read-more\"><a href=\"https:\/\/solidedge.siemens.com\/ja\/customer-story\/gif-module\/\" title=\"Read the Customer Story\"><i class=\"icon-ext\"><\/i>Read the Customer Story<\/a><\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n      \n        <div><!-- slide container -->\n          <div class=\"wpv-resources-item\" data-mh=\".wpv-resources-item\">\n            <div class=\"resources-item-poster\"><a href=\"https:\/\/solidedge.siemens.com\/ja\/customer-story\/medipack\/\" title=\"Read the Customer Story\"><img src=\"https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2018\/04\/c-medipac.jpg\" alt=\"Medipack\" class=\"attachment-resources-poster size-resources-poster wp-post-image\" \/><\/a>\n            <\/div>\n            <div class=\"resources-item-content\">\n              <p class=\"resources-item-meta\">Medipack | India<\/p>\n              <p class=\"resources-item-title\">Customer-specific packaging solutions for medical devices<\/p>\n              <p class=\"resources-item-read-more\"><a href=\"https:\/\/solidedge.siemens.com\/ja\/customer-story\/medipack\/\" title=\"Read the Customer Story\"><i class=\"icon-ext\"><\/i>Read the Customer Story<\/a><\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n      \n        <div><!-- slide container -->\n          <div class=\"wpv-resources-item\" data-mh=\".wpv-resources-item\">\n            <div class=\"resources-item-poster\"><a href=\"https:\/\/solidedge.siemens.com\/ja\/customer-story\/hydrauvision\/\" title=\"Read the Customer Story\"><img src=\"https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2019\/02\/Hydrauvision-480x270.jpg\" alt=\"Hydrauvision\" class=\"attachment-resources-poster size-resources-poster wp-post-image\" \/><\/a>\n            <\/div>\n            <div class=\"resources-item-content\">\n              <p class=\"resources-item-meta\">Hydrauvision<\/p>\n              <p class=\"resources-item-title\">Hydraulic power manufacturer cuts down reliance on prototypes<\/p>\n              <p class=\"resources-item-read-more\"><a href=\"https:\/\/solidedge.siemens.com\/ja\/customer-story\/hydrauvision\/\" title=\"Read the Customer Story\"><i class=\"icon-ext\"><\/i>Read the Customer Story<\/a><\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n      \n        <div><!-- slide container -->\n          <div class=\"wpv-resources-item\" data-mh=\".wpv-resources-item\">\n            <div class=\"resources-item-poster\"><a href=\"https:\/\/solidedge.siemens.com\/ja\/customer-story\/leutenegger-frei-plm-environment\/\" title=\"Read the Customer Story\"><img src=\"https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2018\/04\/c-leutenegger-frei.jpg\" alt=\"Leutenegger + Frei\" class=\"attachment-resources-poster size-resources-poster wp-post-image\" \/><\/a>\n            <\/div>\n            <div class=\"resources-item-content\">\n              <p class=\"resources-item-meta\">Leutenegger + Frei | Switzerland<\/p>\n              <p class=\"resources-item-title\">Two highly successful fields of endeavor \u2013 one PLM environment<\/p>\n              <p class=\"resources-item-read-more\"><a href=\"https:\/\/solidedge.siemens.com\/ja\/customer-story\/leutenegger-frei-plm-environment\/\" title=\"Read the Customer Story\"><i class=\"icon-ext\"><\/i>Read the Customer Story<\/a><\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n      \n        <div><!-- slide container -->\n          <div class=\"wpv-resources-item\" data-mh=\".wpv-resources-item\">\n            <div class=\"resources-item-poster\"><a href=\"https:\/\/resources.sw.siemens.com\/en-US\/case-study-calder\" title=\"Read the Customer Story\"><img src=\"https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2018\/04\/c-calder.jpg\" alt=\"Calder\" class=\"attachment-resources-poster size-resources-poster wp-post-image\" \/><\/a>\n            <\/div>\n            <div class=\"resources-item-content\">\n              <p class=\"resources-item-meta\">Calder | UK<\/p>\n              <p class=\"resources-item-title\">Calder saves time and money<\/p>\n              <p class=\"resources-item-read-more\"><a href=\"https:\/\/resources.sw.siemens.com\/en-US\/case-study-calder\" title=\"Read the Customer Story\"><i class=\"icon-ext\"><\/i>Read the Customer Story<\/a><\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n      \n        <div><!-- slide container -->\n          <div class=\"wpv-resources-item\" data-mh=\".wpv-resources-item\">\n            <div class=\"resources-item-poster\"><a href=\"https:\/\/solidedge.siemens.com\/ja\/customer-story\/spezialfahrzeugbau-tunger\/\" title=\"Read the Customer Story\"><img src=\"https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2019\/05\/spezialfahrzeugbau-1280x720-480x270.jpg\" alt=\"Spezialfahrzeugbau Tunger\" class=\"attachment-resources-poster size-resources-poster wp-post-image\" \/><\/a>\n            <\/div>\n            <div class=\"resources-item-content\">\n              <p class=\"resources-item-meta\">Spezialfahrzeugbau Tunger | Reichenbach, Germany | Automotive & Transportation<\/p>\n              <p class=\"resources-item-title\">Using Solid Edge aids promotional truck designer deliver unique, high-quality vehicles on schedule<\/p>\n              <p class=\"resources-item-read-more\"><a href=\"https:\/\/solidedge.siemens.com\/ja\/customer-story\/spezialfahrzeugbau-tunger\/\" title=\"Read the Customer Story\"><i class=\"icon-ext\"><\/i>Read the Customer Story<\/a><\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n      \n        <div><!-- slide container -->\n          <div class=\"wpv-resources-item\" data-mh=\".wpv-resources-item\">\n            <div class=\"resources-item-poster\"><a href=\"https:\/\/solidedge.siemens.com\/ja\/customer-story\/ipad\/\" title=\"Read the Customer Story\"><img src=\"https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2019\/05\/ipad-69926-1280x720-480x270.jpg\" alt=\"IPAD\" class=\"attachment-resources-poster size-resources-poster wp-post-image\" \/><\/a>\n            <\/div>\n            <div class=\"resources-item-content\">\n              <p class=\"resources-item-meta\">IPAD | Lunca Corbului, Arges, Romania | Automotive & Transportation<\/p>\n              <p class=\"resources-item-title\">Siemens Digital Industries Software solutions enable automotive supplier to reduce average product delivery time by 38 percent<\/p>\n              <p class=\"resources-item-read-more\"><a href=\"https:\/\/solidedge.siemens.com\/ja\/customer-story\/ipad\/\" title=\"Read the Customer Story\"><i class=\"icon-ext\"><\/i>Read the Customer Story<\/a><\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n      \n      \n      <\/div><\/div>\t\t\t<script type=\"text\/javascript\">\r\n\t\t\t\tjQuery(document).ready(function ($) {\r\n\t\t\t\t\tif( typeof jQuery('.ult-carousel-3330854776a977d8f13fe4').slick == \"function\"){\r\n\t\t\t\t\t\t$('.ult-carousel-3330854776a977d8f13fe4').slick({dots: true,autoplaySpeed: 5000,speed: 500,infinite: false,arrows: true,nextArrow: '<button type=\"button\" role=\"button\" aria-label=\"Next\" style=\"color:#ffffff; font-size:30px;background:rgba(47,56,60,0.5);\" class=\"slick-next square-bg\"><i class=\"ultsl-arrow-right6\"><\/i><\/button>',prevArrow: '<button type=\"button\" role=\"button\" aria-label=\"Previous\" style=\"color:#ffffff; font-size:30px;background:rgba(47,56,60,0.5);\" class=\"slick-prev square-bg\"><i class=\"ultsl-arrow-left6\"><\/i><\/button>',slidesToScroll:3,slidesToShow:3,swipe: true,draggable: true,touchMove: true,pauseOnHover: true,pauseOnFocus: false,responsive: [\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t  breakpoint: 1026,\r\n\t\t\t\t\t\t\t  settings: {\r\n\t\t\t\t\t\t\t\tslidesToShow: 3,\r\n\t\t\t\t\t\t\t\tslidesToScroll: 3,  \r\n\t\t\t\t\t\t\t  }\r\n\t\t\t\t\t\t\t},\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t  breakpoint: 1025,\r\n\t\t\t\t\t\t\t  settings: {\r\n\t\t\t\t\t\t\t\tslidesToShow: 2,\r\n\t\t\t\t\t\t\t\tslidesToScroll: 2\r\n\t\t\t\t\t\t\t  }\r\n\t\t\t\t\t\t\t},\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t  breakpoint: 760,\r\n\t\t\t\t\t\t\t  settings: {\r\n\t\t\t\t\t\t\t\tslidesToShow: 1,\r\n\t\t\t\t\t\t\t\tslidesToScroll: 1\r\n\t\t\t\t\t\t\t  }\r\n\t\t\t\t\t\t\t}\r\n\t\t\t\t\t\t],pauseOnDotsHover: true,customPaging: function(slider, i) {\r\n                   return '<i type=\"button\" style= \"color:#788891;\" class=\"ultsl-record\" data-role=\"none\"><\/i>';\r\n                },});\r\n\t\t\t\t\t}\r\n\t\t\t\t});\r\n\t\t\t<\/script>\r\n\t\t\t\n\t<\/div>\n\t\n\t\n<\/div>\n[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; el_class=&#8221;vc-row-related-content&#8221;][vc_column][vc_column_text]<\/p>\n<h2>Related content<\/h2>\n<p>[\/vc_column_text]<div id=\"ult-carousel-20391442576a977d8f1455c\" class=\"ult-carousel-wrapper  vc-el-carousel-related-content ult_horizontal\" data-gutter=\"0\" data-rtl=\"false\" ><div class=\"ult-carousel-9859439246a977d8f1453c \" >[vc_column_text]<a href=\"https:\/\/resources.sw.siemens.com\/en-US\/white-paper-sheet-metal-design-challenges\/\" target=\"_blank\" rel=\"noopener\">White paper: 7 ways to improve your sheet metal design<\/a>[\/vc_column_text][vc_column_text]<a href=\"https:\/\/resources.sw.siemens.com\/en-US\/e-book-four-considerations-when-working-with-sheet-metal\" target=\"_blank\" rel=\"noopener\">eBook: Four considerations when working with sheet metal<\/a>[\/vc_column_text][vc_column_text]<a href=\"https:\/\/community.plm.automation.siemens.com\/t5\/Solid-Edge-Knowledge-Base\/Efficient-Sheet-Metal-Techniques\/ta-p\/320881\">Knowledge base: Efficient sheet metal design techniques<\/a>[\/vc_column_text][vc_column_text]<a href=\"https:\/\/www.siemens.com\/en-us\/products\/designcenter\/solid-edge\/pricing\/\" target=\"_blank\" rel=\"noopener\">Compare Designcenter Solid Edge plans and pricing<\/a>[\/vc_column_text]<\/div><\/div>\t\t\t<script type=\"text\/javascript\">\r\n\t\t\t\tjQuery(document).ready(function ($) {\r\n\t\t\t\t\tif( typeof jQuery('.ult-carousel-9859439246a977d8f1453c').slick == \"function\"){\r\n\t\t\t\t\t\t$('.ult-carousel-9859439246a977d8f1453c').slick({dots: true,autoplaySpeed: 5000,speed: 500,infinite: false,arrows: true,nextArrow: '<button type=\"button\" role=\"button\" aria-label=\"Next\" style=\"color:#ffffff; font-size:30px;background:rgba(255,255,255,0.2);\" class=\"slick-next square-bg\"><i class=\"ultsl-arrow-right6\"><\/i><\/button>',prevArrow: '<button type=\"button\" role=\"button\" aria-label=\"Previous\" style=\"color:#ffffff; font-size:30px;background:rgba(255,255,255,0.2);\" class=\"slick-prev square-bg\"><i class=\"ultsl-arrow-left6\"><\/i><\/button>',slidesToScroll:4,slidesToShow:4,swipe: true,draggable: true,touchMove: true,pauseOnHover: true,pauseOnFocus: false,responsive: [\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t  breakpoint: 1026,\r\n\t\t\t\t\t\t\t  settings: {\r\n\t\t\t\t\t\t\t\tslidesToShow: 4,\r\n\t\t\t\t\t\t\t\tslidesToScroll: 4,  \r\n\t\t\t\t\t\t\t  }\r\n\t\t\t\t\t\t\t},\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t  breakpoint: 1025,\r\n\t\t\t\t\t\t\t  settings: {\r\n\t\t\t\t\t\t\t\tslidesToShow: 2,\r\n\t\t\t\t\t\t\t\tslidesToScroll: 2\r\n\t\t\t\t\t\t\t  }\r\n\t\t\t\t\t\t\t},\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t  breakpoint: 760,\r\n\t\t\t\t\t\t\t  settings: {\r\n\t\t\t\t\t\t\t\tslidesToShow: 1,\r\n\t\t\t\t\t\t\t\tslidesToScroll: 1\r\n\t\t\t\t\t\t\t  }\r\n\t\t\t\t\t\t\t}\r\n\t\t\t\t\t\t],pauseOnDotsHover: true,customPaging: function(slider, i) {\r\n                   return '<i type=\"button\" style= \"color:#ffffff;\" class=\"ultsl-record\" data-role=\"none\"><\/i>';\r\n                },});\r\n\t\t\t\t\t}\r\n\t\t\t\t});\r\n\t\t\t<\/script>\r\n\t\t\t[\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"[vc_row full_width=\"stretch_row\" full_height=\"yes\" cont [...]","protected":false},"author":10,"featured_media":0,"parent":2740,"menu_order":3,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.4.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u677f\u91d1\u8a2d\u8a08 | \u677f\u91d1\u90e8\u54c1 | Solid Edge<\/title>\n<meta name=\"description\" content=\"Solid Edge\u3067\u306f\u3001\u30b7\u30fc\u30c8\u30e1\u30bf\u30eb\u6a5f\u80fd\u3068\u3001\u89e3\u6790\u3084NC\u30d7\u30ed\u30b0\u30e9\u30df\u30f3\u30b0\u7528\u306e\u7d71\u5408\u30a2\u30d7\u30ea\u30b1\u30fc\u30b7\u30e7\u30f3\u306b\u3088\u308a\u3001\u677f\u91d1\u8a2d\u8a08\u304c\u5bb9\u6613\u306b\u884c\u3048\u307e\u3059\u3002\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/solidedge.siemens.com\/ja\/solutions\/products\/3d-design\/sheet-metal-design\/\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u677f\u91d1\u8a2d\u8a08 | \u677f\u91d1\u90e8\u54c1 | Solid Edge\" \/>\n<meta property=\"og:description\" content=\"Solid Edge\u3067\u306f\u3001\u30b7\u30fc\u30c8\u30e1\u30bf\u30eb\u6a5f\u80fd\u3068\u3001\u89e3\u6790\u3084NC\u30d7\u30ed\u30b0\u30e9\u30df\u30f3\u30b0\u7528\u306e\u7d71\u5408\u30a2\u30d7\u30ea\u30b1\u30fc\u30b7\u30e7\u30f3\u306b\u3088\u308a\u3001\u677f\u91d1\u8a2d\u8a08\u304c\u5bb9\u6613\u306b\u884c\u3048\u307e\u3059\u3002\" \/>\n<meta property=\"og:url\" content=\"https:\/\/solidedge.siemens.com\/en\/solutions\/products\/3d-design\/sheet-metal-design\/\" \/>\n<meta property=\"og:site_name\" content=\"Solid Edge\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/solidedge\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-26T17:01:02+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@siemensplm\" \/>\n<meta name=\"twitter:label1\" content=\"\u63a8\u5b9a\u8aad\u66f8\u6642\u9593\" \/>\n\t<meta name=\"twitter:data1\" content=\"10\u5206\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/solidedge.siemens.com\/en\/#organization\",\"name\":\"Siemens Digital Industries Software\",\"url\":\"https:\/\/solidedge.siemens.com\/en\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/solidedge\",\"https:\/\/www.instagram.com\/siemens\/\",\"https:\/\/www.linkedin.com\/company\/siemens-plm-software\",\"https:\/\/www.youtube.com\/user\/PolarionSoftware\",\"https:\/\/twitter.com\/siemensplm\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/solidedge.siemens.com\/en\/#logo\",\"inLanguage\":\"ja\",\"url\":\"https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2018\/04\/logo-siemens-ifl@2x.png\",\"contentUrl\":\"https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2018\/04\/logo-siemens-ifl@2x.png\",\"width\":640,\"height\":270,\"caption\":\"Siemens Digital Industries Software\"},\"image\":{\"@id\":\"https:\/\/solidedge.siemens.com\/en\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/solidedge.siemens.com\/en\/#website\",\"url\":\"https:\/\/solidedge.siemens.com\/en\/\",\"name\":\"Solid Edge\",\"description\":\"Siemens Software\",\"publisher\":{\"@id\":\"https:\/\/solidedge.siemens.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/solidedge.siemens.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"ja\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/solidedge.siemens.com\/en\/solutions\/products\/3d-design\/sheet-metal-design\/#webpage\",\"url\":\"https:\/\/solidedge.siemens.com\/en\/solutions\/products\/3d-design\/sheet-metal-design\/\",\"name\":\"\u677f\u91d1\u8a2d\u8a08 | \u677f\u91d1\u90e8\u54c1 | Solid Edge\",\"isPartOf\":{\"@id\":\"https:\/\/solidedge.siemens.com\/en\/#website\"},\"datePublished\":\"2022-10-12T13:00:22+00:00\",\"dateModified\":\"2026-05-26T17:01:02+00:00\",\"description\":\"Solid Edge\u3067\u306f\u3001\u30b7\u30fc\u30c8\u30e1\u30bf\u30eb\u6a5f\u80fd\u3068\u3001\u89e3\u6790\u3084NC\u30d7\u30ed\u30b0\u30e9\u30df\u30f3\u30b0\u7528\u306e\u7d71\u5408\u30a2\u30d7\u30ea\u30b1\u30fc\u30b7\u30e7\u30f3\u306b\u3088\u308a\u3001\u677f\u91d1\u8a2d\u8a08\u304c\u5bb9\u6613\u306b\u884c\u3048\u307e\u3059\u3002\",\"breadcrumb\":{\"@id\":\"https:\/\/solidedge.siemens.com\/en\/solutions\/products\/3d-design\/sheet-metal-design\/#breadcrumb\"},\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/solidedge.siemens.com\/en\/solutions\/products\/3d-design\/sheet-metal-design\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/solidedge.siemens.com\/en\/solutions\/products\/3d-design\/sheet-metal-design\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/solidedge.siemens.com\/ja\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u30bd\u30ea\u30e5\u30fc\u30b7\u30e7\u30f3\",\"item\":\"https:\/\/solidedge.siemens.com\/ja\/solutions\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u88fd\u54c1\",\"item\":\"https:\/\/solidedge.siemens.com\/ja\/solutions\/products\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"3D\u8a2d\u8a08\",\"item\":\"https:\/\/solidedge.siemens.com\/ja\/solutions\/products\/3d-design\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"\u677f\u91d1\u8a2d\u8a08\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u677f\u91d1\u8a2d\u8a08 | \u677f\u91d1\u90e8\u54c1 | Solid Edge","description":"Solid Edge\u3067\u306f\u3001\u30b7\u30fc\u30c8\u30e1\u30bf\u30eb\u6a5f\u80fd\u3068\u3001\u89e3\u6790\u3084NC\u30d7\u30ed\u30b0\u30e9\u30df\u30f3\u30b0\u7528\u306e\u7d71\u5408\u30a2\u30d7\u30ea\u30b1\u30fc\u30b7\u30e7\u30f3\u306b\u3088\u308a\u3001\u677f\u91d1\u8a2d\u8a08\u304c\u5bb9\u6613\u306b\u884c\u3048\u307e\u3059\u3002","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/solidedge.siemens.com\/ja\/solutions\/products\/3d-design\/sheet-metal-design\/","og_locale":"ja_JP","og_type":"article","og_title":"\u677f\u91d1\u8a2d\u8a08 | \u677f\u91d1\u90e8\u54c1 | Solid Edge","og_description":"Solid Edge\u3067\u306f\u3001\u30b7\u30fc\u30c8\u30e1\u30bf\u30eb\u6a5f\u80fd\u3068\u3001\u89e3\u6790\u3084NC\u30d7\u30ed\u30b0\u30e9\u30df\u30f3\u30b0\u7528\u306e\u7d71\u5408\u30a2\u30d7\u30ea\u30b1\u30fc\u30b7\u30e7\u30f3\u306b\u3088\u308a\u3001\u677f\u91d1\u8a2d\u8a08\u304c\u5bb9\u6613\u306b\u884c\u3048\u307e\u3059\u3002","og_url":"https:\/\/solidedge.siemens.com\/en\/solutions\/products\/3d-design\/sheet-metal-design\/","og_site_name":"Solid Edge","article_publisher":"https:\/\/www.facebook.com\/solidedge","article_modified_time":"2026-05-26T17:01:02+00:00","twitter_card":"summary_large_image","twitter_site":"@siemensplm","twitter_misc":{"\u63a8\u5b9a\u8aad\u66f8\u6642\u9593":"10\u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/solidedge.siemens.com\/en\/#organization","name":"Siemens Digital Industries Software","url":"https:\/\/solidedge.siemens.com\/en\/","sameAs":["https:\/\/www.facebook.com\/solidedge","https:\/\/www.instagram.com\/siemens\/","https:\/\/www.linkedin.com\/company\/siemens-plm-software","https:\/\/www.youtube.com\/user\/PolarionSoftware","https:\/\/twitter.com\/siemensplm"],"logo":{"@type":"ImageObject","@id":"https:\/\/solidedge.siemens.com\/en\/#logo","inLanguage":"ja","url":"https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2018\/04\/logo-siemens-ifl@2x.png","contentUrl":"https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2018\/04\/logo-siemens-ifl@2x.png","width":640,"height":270,"caption":"Siemens Digital Industries Software"},"image":{"@id":"https:\/\/solidedge.siemens.com\/en\/#logo"}},{"@type":"WebSite","@id":"https:\/\/solidedge.siemens.com\/en\/#website","url":"https:\/\/solidedge.siemens.com\/en\/","name":"Solid Edge","description":"Siemens Software","publisher":{"@id":"https:\/\/solidedge.siemens.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/solidedge.siemens.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"ja"},{"@type":"WebPage","@id":"https:\/\/solidedge.siemens.com\/en\/solutions\/products\/3d-design\/sheet-metal-design\/#webpage","url":"https:\/\/solidedge.siemens.com\/en\/solutions\/products\/3d-design\/sheet-metal-design\/","name":"\u677f\u91d1\u8a2d\u8a08 | \u677f\u91d1\u90e8\u54c1 | Solid Edge","isPartOf":{"@id":"https:\/\/solidedge.siemens.com\/en\/#website"},"datePublished":"2022-10-12T13:00:22+00:00","dateModified":"2026-05-26T17:01:02+00:00","description":"Solid Edge\u3067\u306f\u3001\u30b7\u30fc\u30c8\u30e1\u30bf\u30eb\u6a5f\u80fd\u3068\u3001\u89e3\u6790\u3084NC\u30d7\u30ed\u30b0\u30e9\u30df\u30f3\u30b0\u7528\u306e\u7d71\u5408\u30a2\u30d7\u30ea\u30b1\u30fc\u30b7\u30e7\u30f3\u306b\u3088\u308a\u3001\u677f\u91d1\u8a2d\u8a08\u304c\u5bb9\u6613\u306b\u884c\u3048\u307e\u3059\u3002","breadcrumb":{"@id":"https:\/\/solidedge.siemens.com\/en\/solutions\/products\/3d-design\/sheet-metal-design\/#breadcrumb"},"inLanguage":"ja","potentialAction":[{"@type":"ReadAction","target":["https:\/\/solidedge.siemens.com\/en\/solutions\/products\/3d-design\/sheet-metal-design\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/solidedge.siemens.com\/en\/solutions\/products\/3d-design\/sheet-metal-design\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/solidedge.siemens.com\/ja\/"},{"@type":"ListItem","position":2,"name":"\u30bd\u30ea\u30e5\u30fc\u30b7\u30e7\u30f3","item":"https:\/\/solidedge.siemens.com\/ja\/solutions\/"},{"@type":"ListItem","position":3,"name":"\u88fd\u54c1","item":"https:\/\/solidedge.siemens.com\/ja\/solutions\/products\/"},{"@type":"ListItem","position":4,"name":"3D\u8a2d\u8a08","item":"https:\/\/solidedge.siemens.com\/ja\/solutions\/products\/3d-design\/"},{"@type":"ListItem","position":5,"name":"\u677f\u91d1\u8a2d\u8a08"}]}]}},"_links":{"self":[{"href":"https:\/\/solidedge.siemens.com\/ja\/wp-json\/wp\/v2\/pages\/2061"}],"collection":[{"href":"https:\/\/solidedge.siemens.com\/ja\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/solidedge.siemens.com\/ja\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/solidedge.siemens.com\/ja\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/solidedge.siemens.com\/ja\/wp-json\/wp\/v2\/comments?post=2061"}],"version-history":[{"count":5,"href":"https:\/\/solidedge.siemens.com\/ja\/wp-json\/wp\/v2\/pages\/2061\/revisions"}],"predecessor-version":[{"id":69184,"href":"https:\/\/solidedge.siemens.com\/ja\/wp-json\/wp\/v2\/pages\/2061\/revisions\/69184"}],"up":[{"embeddable":true,"href":"https:\/\/solidedge.siemens.com\/ja\/wp-json\/wp\/v2\/pages\/2740"}],"wp:attachment":[{"href":"https:\/\/solidedge.siemens.com\/ja\/wp-json\/wp\/v2\/media?parent=2061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}