{"id":46904,"date":"2021-12-09T11:24:49","date_gmt":"2021-12-09T16:24:49","guid":{"rendered":"https:\/\/solidedge.siemens.com\/?page_id=46904"},"modified":"2022-07-26T13:50:59","modified_gmt":"2022-07-26T17:50:59","slug":"solid-edge-cam","status":"publish","type":"page","link":"https:\/\/solidedge.siemens.com\/fr\/solutions\/products\/computer-aided-manufacturing-cam\/solid-edge-cam\/","title":{"rendered":"Solid Edge CAM Pro"},"content":{"rendered":"<p>[vc_row full_width=\u00a0\u00bbstretch_row\u00a0\u00bb full_height=\u00a0\u00bbyes\u00a0\u00bb el_class=\u00a0\u00bbvc-row-hero-banner\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1631551890992{background-image: url(https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2021\/09\/solid-edge-cam-pro-1920&#215;969-1.jpg?id=47022) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}\u00a0\u00bb][vc_column][vc_column_text el_class=\u00a0\u00bb.vc-el-callout\u00a0\u00bb]<\/p>\n<h1>Solid Edge CAM Pro<\/h1>\n<p><br class=\"xliff-newline\" \/>Con\u00e7u pour les utilisateurs de Solid Edge, Solid Edge CAM Pro propose une gamme compl\u00e8te d\u2019outils qui vous aideront \u00e0 terminer votre t\u00e2che d\u00e8s la premi\u00e8re tentative. Solid Edge CAM Pro est un ensemble flexible et modulable de solutions de programmation \u00e0 commande num\u00e9rique qui vous permet de maximiser la valeur de vos machines-outils. Facile \u00e0 d\u00e9ployer et \u00e0 prendre en main, Solid Edge CAM Pro offre une programmation de commande num\u00e9rique puissante pour un faible co\u00fbt total de possession.<br class=\"xliff-newline\" \/><br class=\"xliff-newline\" \/><a class=\"action-button\" href=\"\/en\/try-now\/\"><i class=\"icon-ext\"><\/i>Essayez Solid Edge gratuitement<\/a>[\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=\u00a0\u00bbstretch_row\u00a0\u00bb equal_height=\u00a0\u00bbyes\u00a0\u00bb el_class=\u00a0\u00bbmore-info-bluebox\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1556640807248{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;padding-bottom: 0px !important;background-color: #006486 !important;}\u00a0\u00bb][vc_column css=\u00a0\u00bb.vc_custom_1556640873153{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;padding-bottom: 0px !important;}\u00a0\u00bb][vc_column_text css=\u00a0\u00bb.vc_custom_1658253091849{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 1em !important;padding-bottom: 1em !important;}\u00a0\u00bb]<\/p>\n<div class=\"lto-bundle-promo-link\"><span style=\"font-size: 20px;\" class=\"c-white\">Pour une dur\u00e9e limit\u00e9e, b\u00e9n\u00e9ficiez de 50 % de r\u00e9duction sur Solid Edge CAM Pro et Solid Edge 2D Nesting.<span style=\"float: right;\"><a class=\"action-button\" href=\"https:\/\/resources.sw.siemens.com\/fr-FR\/get-50-off-computer-aided-manufacturing-cam-and-2d-nesting\" data-wpel-link=\"internal\"><i class=\"icon-ext\"><\/i>Afficher les d\u00e9tails.<\/a><\/span><\/span><\/div>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<h3>Ease-of-use<\/h3>\n<p>An intuitive, modern user interface (UI), easy-to-follow tutorials, built-in templates, and wizard guides make Solid Edge CAM remarkably easy to use. Consistent navigators manage key elements while dialogs provide graphical help and instant feedback in the graphics area.[\/vc_column_text][vc_column_text]<\/p>\n<h3>CAO Neutre<\/h3>\n<p>Anticipez plus efficacement l\u2019impact des modifications de la g\u00e9om\u00e9trie ou des conditions aux limites sur les r\u00e9sultats en comparant un plus grand nombre de variantes pour vos projets. \u00c9valuez les r\u00e9sultats sous forme de valeurs num\u00e9riques, de graphiques ou d\u2019animations.[\/vc_column_text][vc_column_text]<\/p>\n<h3>Postprocessor library<\/h3>\n<p>Included with Solid Edge CAM Pro, the Post Hub library enables a streamlined process to generate production-ready CNC programs for your applications. The searchable, online database lets you access more than 1,200 postprocessors directly from Solid Edge and download them to your workstation.[\/vc_column_text][vc_column_inner width=\u00a0\u00bb1\/2&Prime;][vc_column_text]<\/p>\n<h3>Int\u00e9gration \u00e9troite avec Solid\u00a0Edge<\/h3>\n<p>L\u2019envoi de fichiers depuis Solid Edge vers Solid Edge CAM Pro se fait d\u2019un simple clic. Envoyez un seul fichier ou tout un assemblage pour fabrication. Les donn\u00e9es conservent leur associativit\u00e9\u00a0: si des changements de conception surviennent en phase avanc\u00e9e, ils peuvent \u00eatre facilement int\u00e9gr\u00e9s dans le plan de fabrication.[\/vc_column_text][vc_column_text]<\/p>\n<h3>PMI<\/h3>\n<p>Les informations de fabrication du produit (PMI) sont transf\u00e9r\u00e9es avec les donn\u00e9es de g\u00e9om\u00e9trie de Solid Edge \u00e0 Solid Edge CAM Pro. Ce m\u00e9canisme permet au programmeur CN de concevoir tr\u00e8s facilement le plan de fabrication en fonction des sp\u00e9cifications de l\u2019ing\u00e9nieur.[\/vc_column_text][\/vc_column_inner][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text el_class=\u00a0\u00bbvc-el-lead-in\u00a0\u00bb]Capacit\u00e9s<\/p>\n<h2>Solutions de FAO optimis\u00e9es selon vos besoins<\/h2>\n<p>Utilisez un seul syst\u00e8me de FAO pour votre atelier et faites des \u00e9conomies gr\u00e2ce \u00e0 Solid Edge CAM Pro. La solution modulable offre une large gamme de fonctionnalit\u00e9s de programmation CN avanc\u00e9es pour gagner en flexibilit\u00e9 et maximiser la valeur de vos investissements.<\/p>\n<p>En plus des capacit\u00e9s de fraisage 2,5\u00a0axes incluses dans les contrats de maintenance active Solid Edge Classic, Foundation et Premium, CAM Pro offre des packs 2,5\u00a0axes, 3\u00a0axes et 5\u00a0axes. Ces configurations, ainsi que de nombreuses fonctionnalit\u00e9s compl\u00e9mentaires, vous permettent de personnaliser la solution pour r\u00e9pondre au mieux \u00e0 vos besoins de fabrication sp\u00e9cifiques.[\/vc_column_text]\n\n\n<div id=\"wpv-view-layout-873-CATTR62ccfc3993956678166015a9f3a23c2fTCPID46904\" class=\"js-wpv-view-layout js-wpv-layout-responsive js-wpv-view-layout-873-CATTR62ccfc3993956678166015a9f3a23c2fTCPID46904\" data-viewnumber=\"873-CATTR62ccfc3993956678166015a9f3a23c2fTCPID46904\" data-pagination=\"{&quot;id&quot;:873,&quot;query&quot;:&quot;normal&quot;,&quot;type&quot;:&quot;disabled&quot;,&quot;effect&quot;:&quot;fade&quot;,&quot;duration&quot;:500,&quot;speed&quot;:5,&quot;pause_on_hover&quot;:&quot;disabled&quot;,&quot;stop_rollover&quot;:&quot;false&quot;,&quot;cache_pages&quot;:&quot;enabled&quot;,&quot;preload_images&quot;:&quot;enabled&quot;,&quot;preload_pages&quot;:&quot;enabled&quot;,&quot;preload_reach&quot;:1,&quot;spinner&quot;:&quot;builtin&quot;,&quot;spinner_image&quot;:&quot;https:\/\/solidedge.siemens.com\/wp-content\/plugins\/wp-views\/embedded\/res\/img\/ajax-loader.gif&quot;,&quot;callback_next&quot;:&quot;&quot;,&quot;manage_history&quot;:&quot;disabled&quot;,&quot;has_controls_in_form&quot;:&quot;disabled&quot;,&quot;infinite_tolerance&quot;:&quot;0&quot;,&quot;max_pages&quot;:0,&quot;page&quot;:1,&quot;base_permalink&quot;:&quot;\/fr\/wp-json\/wp\/v2\/pages\/46904?wpv_view_count=873-CATTR62ccfc3993956678166015a9f3a23c2fTCPID46904&amp;wpv_paged=WPV_PAGE_NUM&quot;,&quot;loop&quot;:{&quot;type&quot;:&quot;&quot;,&quot;name&quot;:&quot;&quot;,&quot;data&quot;:[],&quot;id&quot;:0}}\" data-permalink=\"\/fr\/wp-json\/wp\/v2\/pages\/46904?wpv_view_count=873-CATTR62ccfc3993956678166015a9f3a23c2fTCPID46904\">\n\n\t\n\t<!-- Attribute 'columns' defines the responsive cols -->\n    <div class=\"wpv-subnavigation-links row\" data-cols=\"2\" data-class=\"col-sm-6 \">\n      \n      \n        <a class=\"wpv-subnavigation-links-item\" data-mh=\"wpv-subnavigation-links-item\" href=\"https:\/\/solidedge.siemens.com\/fr\/solutions\/products\/computer-aided-manufacturing-cam\/solid-edge-cam\/feature-based-machining\/\">Feature-Based Machining<\/a>\n      \n        <a class=\"wpv-subnavigation-links-item\" data-mh=\"wpv-subnavigation-links-item\" href=\"https:\/\/solidedge.siemens.com\/fr\/solutions\/products\/computer-aided-manufacturing-cam\/solid-edge-cam\/milling\/\">Milling<\/a>\n      \n        <a class=\"wpv-subnavigation-links-item\" data-mh=\"wpv-subnavigation-links-item\" href=\"https:\/\/solidedge.siemens.com\/fr\/solutions\/products\/computer-aided-manufacturing-cam\/solid-edge-cam\/nc-simulation\/\">NC Simulation<\/a>\n      \n        <a class=\"wpv-subnavigation-links-item\" data-mh=\"wpv-subnavigation-links-item\" href=\"https:\/\/solidedge.siemens.com\/fr\/solutions\/products\/computer-aided-manufacturing-cam\/solid-edge-cam\/turning\/\">Turning<\/a>\n      \n      \n    <\/div>\n\t\n\t\n<\/div>\n[vc_column_text]<\/p>\n<p style=\"text-align: right;\"><a class=\"action-button transparent\" href=\"https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2021\/09\/Siemens-SW-Solid-Edge-CAM-Pro-FS-78035-D9.pdf\" target=\"_blank\" rel=\"external noopener noreferrer\" data-wpel-link=\"external\"><i class=\"icon-ext\"><\/i>T\u00e9l\u00e9charger la fiche technique Solid Edge CAM Pro<\/a><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=\u00a0\u00bbstretch_row\u00a0\u00bb el_class=\u00a0\u00bbvc-row-video-highlight\u00a0\u00bb][vc_column][vc_column_text el_class=\u00a0\u00bbvc-el-lead-in\u00a0\u00bb]Video<\/p>\n<h2>See Solid Edge CAM in action<\/h2>\n<p class=\"see-more\" style=\"text-align: right;\"><a href=\"https:\/\/solidedge.siemens.com\/fr\/resources\/resource-library\/#ui_Videos\">See More Videos<\/a><\/p>\n<p>[\/vc_column_text]\n\n\n  <div id=\"wpv-view-layout-567-CATTRe18ec719a60a158b21fc4e2f0c0593b9\" class=\"js-wpv-view-layout js-wpv-layout-responsive js-wpv-view-layout-567-CATTRe18ec719a60a158b21fc4e2f0c0593b9\" data-viewnumber=\"567-CATTRe18ec719a60a158b21fc4e2f0c0593b9\" data-pagination=\"{&quot;id&quot;:567,&quot;query&quot;:&quot;normal&quot;,&quot;type&quot;:&quot;disabled&quot;,&quot;effect&quot;:&quot;fade&quot;,&quot;duration&quot;:500,&quot;speed&quot;:5,&quot;pause_on_hover&quot;:&quot;disabled&quot;,&quot;stop_rollover&quot;:&quot;false&quot;,&quot;cache_pages&quot;:&quot;enabled&quot;,&quot;preload_images&quot;:&quot;enabled&quot;,&quot;preload_pages&quot;:&quot;enabled&quot;,&quot;preload_reach&quot;:1,&quot;spinner&quot;:&quot;builtin&quot;,&quot;spinner_image&quot;:&quot;https:\/\/solidedge.siemens.com\/wp-content\/plugins\/wp-views\/embedded\/res\/img\/ajax-loader.gif&quot;,&quot;callback_next&quot;:&quot;&quot;,&quot;manage_history&quot;:&quot;disabled&quot;,&quot;has_controls_in_form&quot;:&quot;disabled&quot;,&quot;infinite_tolerance&quot;:&quot;0&quot;,&quot;max_pages&quot;:0,&quot;page&quot;:1,&quot;base_permalink&quot;:&quot;\/fr\/wp-json\/wp\/v2\/pages\/46904?wpv_view_count=567-CATTRe18ec719a60a158b21fc4e2f0c0593b9&amp;wpv_paged=WPV_PAGE_NUM&quot;,&quot;loop&quot;:{&quot;type&quot;:&quot;&quot;,&quot;name&quot;:&quot;&quot;,&quot;data&quot;:[],&quot;id&quot;:0}}\" data-permalink=\"\/fr\/wp-json\/wp\/v2\/pages\/46904?wpv_view_count=567-CATTRe18ec719a60a158b21fc4e2f0c0593b9\">\n\n  \n  <div class=\"wpv-resources\"><a name=\"video\" class=\"video-anchor\"><\/a>\n    <div id=\"ult-carousel-19237632056a0452057f7e7\" class=\"ult-carousel-wrapper  vc-el-carousel-videos-embedded ult_horizontal\" data-gutter=\"0\" data-rtl=\"false\" ><div class=\"ult-carousel-2686557256a0452057f7c3 \" >\n    \n    \n       <div><!-- slide container -->\n        <div class=\"wpv-resources-item\" data-mh=\".wpv-resources-item\">\n          <div class=\"resources-item-poster\">\n              <div id=\"wpfp_0194c8272585e16ef5a757a53a35f200\" data-item=\"{&quot;sources&quot;:&#091;{&quot;src&quot;:&quot;https:\\\/\\\/videos.mentor-cdn.com\\\/mgc\\\/videos\\\/5400\\\/a4bbae27-756d-4f84-884c-04c66b65b74f-en-US-video.mp4&quot;,&quot;type&quot;:&quot;video\\\/mp4&quot;}&#093;}\" class=\"flowplayer no-brand is-splash no-svg is-paused skin-slim fp-slim fp-edgy\" data-embed=\"false\" style=\"max-width: 1140px; max-height: 640px; background-image: url(https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2021\/09\/a4bbae27-756d-4f84-884c-04c66b65b74f-en-US-thumbnail.png);\" data-ratio=\"0.5614\" data-advance=\"false\">\n\t<div class=\"fp-ratio\" style=\"padding-top: 56.14%\"><\/div>\n\t<div class=\"fp-ui\"><div class=\"fp-play fp-visible\"><a class=\"fp-icon fp-playbtn\"><\/a><\/div><\/div>\n\n<\/div>\n\n              \n          <\/div>\n        <\/div>\n      <\/div>\n    \n    \n    <\/div><\/div>\t\t\t<script type=\"text\/javascript\">\r\n\t\t\t\tjQuery(document).ready(function ($) {\r\n\t\t\t\t\tif( typeof jQuery('.ult-carousel-2686557256a0452057f7c3').slick == \"function\"){\r\n\t\t\t\t\t\t$('.ult-carousel-2686557256a0452057f7c3').slick({dots: true,autoplaySpeed: 5000,speed: 500,infinite: false,arrows: true,nextArrow: '<button type=\"button\" role=\"button\" aria-label=\"Next\" style=\"color:#ffffff; font-size:30px;background:rgba(47,56,60,0.5);\" class=\"slick-next square-bg\"><i class=\"ultsl-arrow-right6\"><\/i><\/button>',prevArrow: '<button type=\"button\" role=\"button\" aria-label=\"Previous\" style=\"color:#ffffff; font-size:30px;background:rgba(47,56,60,0.5);\" class=\"slick-prev square-bg\"><i class=\"ultsl-arrow-left6\"><\/i><\/button>',slidesToScroll:1,slidesToShow:1,swipe: true,draggable: true,touchMove: true,pauseOnHover: true,pauseOnFocus: false,responsive: [\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t  breakpoint: 1026,\r\n\t\t\t\t\t\t\t  settings: {\r\n\t\t\t\t\t\t\t\tslidesToShow: 1,\r\n\t\t\t\t\t\t\t\tslidesToScroll: 1,  \r\n\t\t\t\t\t\t\t  }\r\n\t\t\t\t\t\t\t},\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t  breakpoint: 1025,\r\n\t\t\t\t\t\t\t  settings: {\r\n\t\t\t\t\t\t\t\tslidesToShow: 1,\r\n\t\t\t\t\t\t\t\tslidesToScroll: 1\r\n\t\t\t\t\t\t\t  }\r\n\t\t\t\t\t\t\t},\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t  breakpoint: 760,\r\n\t\t\t\t\t\t\t  settings: {\r\n\t\t\t\t\t\t\t\tslidesToShow: 1,\r\n\t\t\t\t\t\t\t\tslidesToScroll: 1\r\n\t\t\t\t\t\t\t  }\r\n\t\t\t\t\t\t\t}\r\n\t\t\t\t\t\t],pauseOnDotsHover: true,customPaging: function(slider, i) {\r\n                   return '<i type=\"button\" style= \"color:#788891;\" class=\"ultsl-record\" data-role=\"none\"><\/i>';\r\n                },});\r\n\t\t\t\t\t}\r\n\t\t\t\t});\r\n\t\t\t<\/script>\r\n\t\t\t\n  <\/div>\n  \n  \n  <\/div>\n[vc_column_text el_class=\u00a0\u00bbvideo-caption\u00a0\u00bb]<\/p>\n<h3>Donner de la valeur ajout\u00e9e \u00e0 vos machines-outils<\/h3>\n<p>Transformez votre fabrication et optimisez vos donn\u00e9es de conception gr\u00e2ce aux puissants outils automatis\u00e9s des solutions de CAO et FAO enti\u00e8rement int\u00e9gr\u00e9es de Solid Edge.[\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=\u00a0\u00bbstretch_row\u00a0\u00bb el_class=\u00a0\u00bbvc-row-free-software\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1523912493378{background-color: #006486 !important;}\u00a0\u00bb][vc_column][vc_column_text el_class=\u00a0\u00bbvc-el-lead-in\u00a0\u00bb]Offres<\/p>\n<h2>Logiciels de FAO Solid Edge gratuits<\/h2>\n<p>[\/vc_column_text][vc_row_inner equal_height=\u00a0\u00bbyes\u00a0\u00bb][vc_column_inner width=\u00a0\u00bb1\/2&Prime; offset=\u00a0\u00bbvc_col-md-5&Prime;]<div class=\"wpb_content_block wpb_content_element\"><div class=\"wpb_wrapper\"><\/div><\/div>[\/vc_column_inner][vc_column_inner width=\u00a0\u00bb1\/2&Prime; offset=\u00a0\u00bbvc_col-md-offset-2 vc_col-md-5&Prime;]<div class=\"wpb_content_block wpb_content_element\"><div class=\"wpb_wrapper\"><div class=\"content_block\" id=\"custom_post_widget-419\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<h3>Logiciel gratuit pour votre startup<\/h3>\n<p>Si vous dirigez une startup depuis moins de trois ans, vous pouvez maintenant faire une demande pour obtenir gratuitement Solid Edge. Aucun frais \u00e0 votre charge\u00a0![\/vc_column_text][vc_column_text]<a class=\"action-button\" href=\"https:\/\/www.plm.automation.siemens.com\/global\/fr\/topic\/solid-edge-for-startups\/8335\"><i class=\"icon-ext\"><\/i>Postuler<\/a>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div><\/div><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=\u00a0\u00bbstretch_row\u00a0\u00bb el_class=\u00a0\u00bbvc-row-related-content\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1524184785822{background-color: #347eb5 !important;}\u00a0\u00bb][vc_column][vc_column_text]<\/p>\n<h2>Contenu associ\u00e9<\/h2>\n<p>[\/vc_column_text]<div id=\"ult-carousel-827921236a045205814fb\" class=\"ult-carousel-wrapper  vc-el-carousel-related-content ult_horizontal\" data-gutter=\"0\" data-rtl=\"false\" ><div class=\"ult-carousel-2996252026a045205814df \" >[vc_column_text]<a href=\"https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2021\/09\/Siemens-SW-Solid-Edge-CAM-Pro-FS-78035-D9.pdf\" target=\"_blank\" rel=\"noopener\">Fiche technique Solid Edge CAM Pro<\/a>[\/vc_column_text][vc_column_text]<a href=\"https:\/\/www.plm.automation.siemens.com\/plmapp\/education\/solid-edge-cam-pro\/en_us\/free-software\/student\" target=\"_blank\" rel=\"noopener\">Solid Edge CAM Pro Student Edition<\/a>[\/vc_column_text][vc_column_text]<a href=\"https:\/\/community.sw.siemens.com\/s\/topic\/0TO4O000000MihiWAC\/solid-edge\" target=\"_blank\" rel=\"noopener\">Communaut\u00e9 en ligne Solid Edge<\/a>[\/vc_column_text][vc_column_text]<a href=\"https:\/\/blogs.sw.siemens.com\/solidedge\/\" target=\"_blank\" rel=\"noopener\">Blog Solid Edge<\/a>[\/vc_column_text]<\/div><\/div>\t\t\t<script type=\"text\/javascript\">\r\n\t\t\t\tjQuery(document).ready(function ($) {\r\n\t\t\t\t\tif( typeof jQuery('.ult-carousel-2996252026a045205814df').slick == \"function\"){\r\n\t\t\t\t\t\t$('.ult-carousel-2996252026a045205814df').slick({dots: true,autoplaySpeed: 5000,speed: 500,infinite: false,arrows: true,nextArrow: '<button type=\"button\" role=\"button\" aria-label=\"Next\" style=\"color:#ffffff; font-size:30px;background:rgba(255,255,255,0.2);\" class=\"slick-next square-bg\"><i class=\"ultsl-arrow-right6\"><\/i><\/button>',prevArrow: '<button type=\"button\" role=\"button\" aria-label=\"Previous\" style=\"color:#ffffff; font-size:30px;background:rgba(255,255,255,0.2);\" class=\"slick-prev square-bg\"><i class=\"ultsl-arrow-left6\"><\/i><\/button>',slidesToScroll:4,slidesToShow:4,swipe: true,draggable: true,touchMove: true,pauseOnHover: true,pauseOnFocus: false,responsive: [\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t  breakpoint: 1026,\r\n\t\t\t\t\t\t\t  settings: {\r\n\t\t\t\t\t\t\t\tslidesToShow: 4,\r\n\t\t\t\t\t\t\t\tslidesToScroll: 4,  \r\n\t\t\t\t\t\t\t  }\r\n\t\t\t\t\t\t\t},\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t  breakpoint: 1025,\r\n\t\t\t\t\t\t\t  settings: {\r\n\t\t\t\t\t\t\t\tslidesToShow: 2,\r\n\t\t\t\t\t\t\t\tslidesToScroll: 2\r\n\t\t\t\t\t\t\t  }\r\n\t\t\t\t\t\t\t},\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t  breakpoint: 760,\r\n\t\t\t\t\t\t\t  settings: {\r\n\t\t\t\t\t\t\t\tslidesToShow: 1,\r\n\t\t\t\t\t\t\t\tslidesToScroll: 1\r\n\t\t\t\t\t\t\t  }\r\n\t\t\t\t\t\t\t}\r\n\t\t\t\t\t\t],pauseOnDotsHover: true,customPaging: function(slider, i) {\r\n                   return '<i type=\"button\" style= \"color:#ffffff;\" class=\"ultsl-record\" data-role=\"none\"><\/i>';\r\n                },});\r\n\t\t\t\t\t}\r\n\t\t\t\t});\r\n\t\t\t<\/script>\r\n\t\t\t[\/vc_column][\/vc_row][vc_row full_width=\u00a0\u00bbstretch_row\u00a0\u00bb el_class=\u00a0\u00bbfooter-contact\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1550170708528{background-color: #dedee3 !important;}\u00a0\u00bb][vc_column]<div class=\"wpb_content_block wpb_content_element\"><div class=\"wpb_wrapper\"><\/div><\/div>[\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p> Solid Edge CAM Pro Con\u00e7u pour les utilisateurs de Solid Edge, Solid Edge CAM Pro propose une gamme compl\u00e8te d\u2019outils qui vous aideront \u00e0 terminer votre t\u00e2che d\u00e8s la premi\u00e8re tentative. Solid Edge CAM Pro est un ensemble flexible et modulable [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":0,"parent":2590,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.4.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Solid Edge CAM Pro | Programmation CN | Siemens<\/title>\n<meta name=\"description\" content=\"Solid Edge CAM Pro est un ensemble flexible et modulable de solutions de programmation \u00e0 commande num\u00e9rique qui vous permet de maximiser la valeur de vos machines-outils.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/solidedge.siemens.com\/fr\/solutions\/products\/computer-aided-manufacturing-cam\/solid-edge-cam\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Solid Edge CAM Pro | Programmation CN | Siemens\" \/>\n<meta property=\"og:description\" content=\"Solid Edge CAM Pro est un ensemble flexible et modulable de solutions de programmation \u00e0 commande num\u00e9rique qui vous permet de maximiser la valeur de vos machines-outils.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/solidedge.siemens.com\/fr\/solutions\/products\/computer-aided-manufacturing-cam\/solid-edge-cam\/\" \/>\n<meta property=\"og:site_name\" content=\"Solid Edge\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/solidedge\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-26T17:50:59+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@siemensplm\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/solidedge.siemens.com\/en\/#organization\",\"name\":\"Siemens Digital Industries Software\",\"url\":\"https:\/\/solidedge.siemens.com\/en\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/solidedge\",\"https:\/\/www.instagram.com\/siemens\/\",\"https:\/\/www.linkedin.com\/company\/siemens-plm-software\",\"https:\/\/www.youtube.com\/user\/PolarionSoftware\",\"https:\/\/twitter.com\/siemensplm\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/solidedge.siemens.com\/en\/#logo\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2018\/04\/logo-siemens-ifl@2x.png\",\"contentUrl\":\"https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2018\/04\/logo-siemens-ifl@2x.png\",\"width\":640,\"height\":270,\"caption\":\"Siemens Digital Industries Software\"},\"image\":{\"@id\":\"https:\/\/solidedge.siemens.com\/en\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/solidedge.siemens.com\/en\/#website\",\"url\":\"https:\/\/solidedge.siemens.com\/en\/\",\"name\":\"Solid Edge\",\"description\":\"Siemens Digital Industries Software - Ingenuity for Life\",\"publisher\":{\"@id\":\"https:\/\/solidedge.siemens.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/solidedge.siemens.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/solidedge.siemens.com\/fr\/solutions\/products\/computer-aided-manufacturing-cam\/solid-edge-cam\/#webpage\",\"url\":\"https:\/\/solidedge.siemens.com\/fr\/solutions\/products\/computer-aided-manufacturing-cam\/solid-edge-cam\/\",\"name\":\"Solid Edge CAM Pro | Programmation CN | Siemens\",\"isPartOf\":{\"@id\":\"https:\/\/solidedge.siemens.com\/en\/#website\"},\"datePublished\":\"2021-12-09T16:24:49+00:00\",\"dateModified\":\"2022-07-26T17:50:59+00:00\",\"description\":\"Solid Edge CAM Pro est un ensemble flexible et modulable de solutions de programmation \u00e0 commande num\u00e9rique qui vous permet de maximiser la valeur de vos machines-outils.\",\"breadcrumb\":{\"@id\":\"https:\/\/solidedge.siemens.com\/fr\/solutions\/products\/computer-aided-manufacturing-cam\/solid-edge-cam\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/solidedge.siemens.com\/fr\/solutions\/products\/computer-aided-manufacturing-cam\/solid-edge-cam\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/solidedge.siemens.com\/fr\/solutions\/products\/computer-aided-manufacturing-cam\/solid-edge-cam\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/solidedge.siemens.com\/en\/home-6\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Solutions\",\"item\":\"https:\/\/solidedge.siemens.com\/fr\/solutions\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Produits\",\"item\":\"https:\/\/solidedge.siemens.com\/fr\/solutions\/products\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Fabrication assist&eacute;e par ordinateur (FAO)\",\"item\":\"https:\/\/solidedge.siemens.com\/fr\/solutions\/products\/computer-aided-manufacturing-cam\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Solid Edge CAM Pro\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Solid Edge CAM Pro | Programmation CN | Siemens","description":"Solid Edge CAM Pro est un ensemble flexible et modulable de solutions de programmation \u00e0 commande num\u00e9rique qui vous permet de maximiser la valeur de vos machines-outils.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/solidedge.siemens.com\/fr\/solutions\/products\/computer-aided-manufacturing-cam\/solid-edge-cam\/","og_locale":"fr_FR","og_type":"article","og_title":"Solid Edge CAM Pro | Programmation CN | Siemens","og_description":"Solid Edge CAM Pro est un ensemble flexible et modulable de solutions de programmation \u00e0 commande num\u00e9rique qui vous permet de maximiser la valeur de vos machines-outils.","og_url":"https:\/\/solidedge.siemens.com\/fr\/solutions\/products\/computer-aided-manufacturing-cam\/solid-edge-cam\/","og_site_name":"Solid Edge","article_publisher":"https:\/\/www.facebook.com\/solidedge","article_modified_time":"2022-07-26T17:50:59+00:00","twitter_card":"summary_large_image","twitter_site":"@siemensplm","twitter_misc":{"Dur\u00e9e de lecture est.":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/solidedge.siemens.com\/en\/#organization","name":"Siemens Digital Industries Software","url":"https:\/\/solidedge.siemens.com\/en\/","sameAs":["https:\/\/www.facebook.com\/solidedge","https:\/\/www.instagram.com\/siemens\/","https:\/\/www.linkedin.com\/company\/siemens-plm-software","https:\/\/www.youtube.com\/user\/PolarionSoftware","https:\/\/twitter.com\/siemensplm"],"logo":{"@type":"ImageObject","@id":"https:\/\/solidedge.siemens.com\/en\/#logo","inLanguage":"fr-FR","url":"https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2018\/04\/logo-siemens-ifl@2x.png","contentUrl":"https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2018\/04\/logo-siemens-ifl@2x.png","width":640,"height":270,"caption":"Siemens Digital Industries Software"},"image":{"@id":"https:\/\/solidedge.siemens.com\/en\/#logo"}},{"@type":"WebSite","@id":"https:\/\/solidedge.siemens.com\/en\/#website","url":"https:\/\/solidedge.siemens.com\/en\/","name":"Solid Edge","description":"Siemens Digital Industries Software - Ingenuity for Life","publisher":{"@id":"https:\/\/solidedge.siemens.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/solidedge.siemens.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/solidedge.siemens.com\/fr\/solutions\/products\/computer-aided-manufacturing-cam\/solid-edge-cam\/#webpage","url":"https:\/\/solidedge.siemens.com\/fr\/solutions\/products\/computer-aided-manufacturing-cam\/solid-edge-cam\/","name":"Solid Edge CAM Pro | Programmation CN | Siemens","isPartOf":{"@id":"https:\/\/solidedge.siemens.com\/en\/#website"},"datePublished":"2021-12-09T16:24:49+00:00","dateModified":"2022-07-26T17:50:59+00:00","description":"Solid Edge CAM Pro est un ensemble flexible et modulable de solutions de programmation \u00e0 commande num\u00e9rique qui vous permet de maximiser la valeur de vos machines-outils.","breadcrumb":{"@id":"https:\/\/solidedge.siemens.com\/fr\/solutions\/products\/computer-aided-manufacturing-cam\/solid-edge-cam\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/solidedge.siemens.com\/fr\/solutions\/products\/computer-aided-manufacturing-cam\/solid-edge-cam\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/solidedge.siemens.com\/fr\/solutions\/products\/computer-aided-manufacturing-cam\/solid-edge-cam\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/solidedge.siemens.com\/en\/home-6\/"},{"@type":"ListItem","position":2,"name":"Solutions","item":"https:\/\/solidedge.siemens.com\/fr\/solutions\/"},{"@type":"ListItem","position":3,"name":"Produits","item":"https:\/\/solidedge.siemens.com\/fr\/solutions\/products\/"},{"@type":"ListItem","position":4,"name":"Fabrication assist&eacute;e par ordinateur (FAO)","item":"https:\/\/solidedge.siemens.com\/fr\/solutions\/products\/computer-aided-manufacturing-cam\/"},{"@type":"ListItem","position":5,"name":"Solid Edge CAM Pro"}]}]}},"_links":{"self":[{"href":"https:\/\/solidedge.siemens.com\/fr\/wp-json\/wp\/v2\/pages\/46904"}],"collection":[{"href":"https:\/\/solidedge.siemens.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/solidedge.siemens.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/solidedge.siemens.com\/fr\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/solidedge.siemens.com\/fr\/wp-json\/wp\/v2\/comments?post=46904"}],"version-history":[{"count":12,"href":"https:\/\/solidedge.siemens.com\/fr\/wp-json\/wp\/v2\/pages\/46904\/revisions"}],"predecessor-version":[{"id":60771,"href":"https:\/\/solidedge.siemens.com\/fr\/wp-json\/wp\/v2\/pages\/46904\/revisions\/60771"}],"up":[{"embeddable":true,"href":"https:\/\/solidedge.siemens.com\/fr\/wp-json\/wp\/v2\/pages\/2590"}],"wp:attachment":[{"href":"https:\/\/solidedge.siemens.com\/fr\/wp-json\/wp\/v2\/media?parent=46904"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}