{"id":2555,"date":"2019-04-01T10:22:21","date_gmt":"2019-04-01T14:22:21","guid":{"rendered":"https:\/\/solidedge.siemens.com\/designers-and-engineers\/"},"modified":"2021-04-20T15:19:12","modified_gmt":"2021-04-20T19:19:12","slug":"designers-and-engineers","status":"publish","type":"page","link":"https:\/\/solidedge.siemens.com\/de\/solutions\/products\/complete-product-development-portfolio\/designers-and-engineers\/","title":{"rendered":"Konstrukteure und Ingenieure"},"content":{"rendered":"<p>[vc_row full_width=&#8220;stretch_row&#8220; full_height=&#8220;yes&#8220; content_placement=&#8220;middle&#8220; css=&#8220;.vc_custom_1566328422622{background: #a6a6a6 url(https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2019\/08\/ten-kate-header.jpg?id=20115) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8220; el_class=&#8220;vc-row-hero-shoutbox&#8220;][vc_column][vc_column_text el_class=&#8220;.vc-el-callout&#8220;]<\/p>\n<h1>Rennen gewinnen<br \/>\ndurch besseres CAD<\/h1>\n<p>Solid Edge f&ouml;rdert Innovationen und bietet grenzenlose Konstruktionsfreiheit. Synchronous Technology hilft Ihnen, schneller und intelligenter zu konstruieren, und eliminiert zugleich die Beschr&auml;nkungen der herk&ouml;mmlichen 3D-Modellierung. Mit Solid Edge bekommen Sie eine voll funktionale L&ouml;sung f&uuml;r mobile Konstruktion und Zusammenarbeit mit universellem Zugriff auf Konstruktionsprozesse zu jeder Zeit und an jedem Ort.&nbsp; &Uuml;ber die unterschiedlichen Kaufoptionen k&ouml;nnen Sie ein leistungsstarkes, intuitives 3D-Konstruktionsportfolio bereitstellen, das perfekt auf Ihre Gesch&auml;ftsanforderungen zugeschnitten ist.[\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=&#8220;stretch_row&#8220; equal_height=&#8220;yes&#8220; content_placement=&#8220;middle&#8220; css=&#8220;.vc_custom_1524576576786{background-color: #ecf0f5 !important;}&#8220; el_class=&#8220;vc-row-alternating-image-rows image-right&#8220;][vc_column width=&#8220;2\/3&#8243;][vc_column_text el_class=&#8220;vc-el-lead-in&#8220;]White Paper<\/p>\n<h2>F&uuml;nf Tipps f&uuml;r gro&szlig;e Baugruppen<\/h2>\n<p>Ob Ihre Baugruppe aus 1.000 oder 100.000 Teilen besteht, in diesem White Paper finden Sie f&uuml;nf Strategien, die Sie sofort in die Praxis umsetzen k&ouml;nnen, um die Baugruppenperformance zu verbessern, und obendrein lernen Sie bew&auml;hrte Verfahren f&uuml;r die Modellierung und Verwaltung von CAD-Baugruppen aller Gr&ouml;&szlig;en.<\/p>\n<p>[\/vc_column_text][vc_column_text]<a class=\"action-button transparent\" href=\"https:\/\/www.plm.automation.siemens.com\/global\/en\/topic\/se-large-assembly-performance\/2697\"><i class=\"icon-ext\"><\/i>Jetzt herunterladen<\/a><br \/>\n[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/3&#8243;][vc_single_image image=&#8220;1072&#8243; img_size=&#8220;full&#8220; alignment=&#8220;center&#8220;][\/vc_column][\/vc_row][vc_row full_width=&#8220;stretch_row&#8220; equal_height=&#8220;yes&#8220; content_placement=&#8220;middle&#8220; el_class=&#8220;vc-row-alternating-image-rows image-right&#8220;][vc_column width=&#8220;1\/3&#8243;][vc_single_image image=&#8220;1071&#8243; img_size=&#8220;full&#8220; alignment=&#8220;center&#8220;][\/vc_column][vc_column width=&#8220;2\/3&#8243;][vc_column_text el_class=&#8220;vc-el-lead-in&#8220;]White Paper<\/p>\n<h2>CAD-Zeichnungen: Erlernen Sie  die wichtigsten Techniken<\/h2>\n<p>Egal, ob Sie ein erfahrener Zeichner sind oder erst am Anfang stehen &ndash; dieses White Paper wird Ihnen helfen, Ihre Zeichentechniken zu verfeinern, um die Fertigungstauglichkeit Ihrer CAD-Zeichnungen zu verbessern.<\/p>\n<p>[\/vc_column_text][vc_column_text]<a class=\"action-button transparent\" href=\"https:\/\/www.plm.automation.siemens.com\/global\/en\/topic\/cad-drawings\/10514\"><i class=\"icon-ext\"><\/i>Jetzt herunterladen<\/a>[\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=&#8220;stretch_row&#8220; equal_height=&#8220;yes&#8220; content_placement=&#8220;middle&#8220; css=&#8220;.vc_custom_1524576604370{background-color: #ecf0f5 !important;}&#8220; el_class=&#8220;vc-row-alternating-image-rows image-right&#8220;][vc_column width=&#8220;2\/3&#8243;][vc_column_text el_class=&#8220;vc-el-lead-in&#8220;]E-Book<\/p>\n<h2>Vier Tipps f&uuml;r die Blechkonstruktion<\/h2>\n<p>Wie k&ouml;nnen moderne Tools die Arbeit mit Blechen w&auml;hrend Konstruktion und Fertigung erleichtern? In diesem neuen E-Book vom Branchenexperten DEVELOP3D werden vier Aspekte beschrieben, die Sie bei der Arbeit mit Blechen beachten sollten.<br \/>\n[\/vc_column_text][vc_column_text]<a class=\"action-button transparent\" href=\"https:\/\/www.plm.automation.siemens.com\/global\/en\/topic\/sheet-metal-design\/2667\"><i class=\"icon-ext\"><\/i>Weitere Informationen<\/a>[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/3&#8243;][vc_single_image image=&#8220;1073&#8243; img_size=&#8220;full&#8220; alignment=&#8220;center&#8220;][\/vc_column][\/vc_row][vc_row full_width=&#8220;stretch_row&#8220; el_class=&#8220;vc-row-video-highlight&#8220;][vc_column][vc_column_text el_class=&#8220;vc-el-lead-in&#8220;]Video<\/p>\n<h2>Geschwindigkeit und Flexibilit&auml;t in der Konstruktion<\/h2>\n<p class=\"see-more\" style=\"text-align: right;\"><a href=\"https:\/\/solidedge.siemens.com\/de\/resources\/videos\/\">Weitere Videos anzeigen<\/a><\/p>\n<p>[\/vc_column_text]\n\n\n  <div id=\"wpv-view-layout-567-CATTR085b591c9b22f4ecced14675fe5e5334\" class=\"js-wpv-view-layout js-wpv-layout-responsive js-wpv-view-layout-567-CATTR085b591c9b22f4ecced14675fe5e5334\" data-viewnumber=\"567-CATTR085b591c9b22f4ecced14675fe5e5334\" data-pagination=\"{&quot;id&quot;:567,&quot;query&quot;:&quot;normal&quot;,&quot;type&quot;:&quot;disabled&quot;,&quot;effect&quot;:&quot;fade&quot;,&quot;duration&quot;:500,&quot;speed&quot;:5,&quot;pause_on_hover&quot;:&quot;disabled&quot;,&quot;stop_rollover&quot;:&quot;false&quot;,&quot;cache_pages&quot;:&quot;enabled&quot;,&quot;preload_images&quot;:&quot;enabled&quot;,&quot;preload_pages&quot;:&quot;enabled&quot;,&quot;preload_reach&quot;:1,&quot;spinner&quot;:&quot;builtin&quot;,&quot;spinner_image&quot;:&quot;https:\/\/solidedge.siemens.com\/wp-content\/plugins\/wp-views\/embedded\/res\/img\/ajax-loader.gif&quot;,&quot;callback_next&quot;:&quot;&quot;,&quot;manage_history&quot;:&quot;disabled&quot;,&quot;has_controls_in_form&quot;:&quot;disabled&quot;,&quot;infinite_tolerance&quot;:&quot;0&quot;,&quot;max_pages&quot;:0,&quot;page&quot;:1,&quot;base_permalink&quot;:&quot;\/de\/wp-json\/wp\/v2\/pages\/2555?wpv_view_count=567-CATTR085b591c9b22f4ecced14675fe5e5334&amp;wpv_paged=WPV_PAGE_NUM&quot;,&quot;loop&quot;:{&quot;type&quot;:&quot;&quot;,&quot;name&quot;:&quot;&quot;,&quot;data&quot;:[],&quot;id&quot;:0}}\" data-permalink=\"\/de\/wp-json\/wp\/v2\/pages\/2555?wpv_view_count=567-CATTR085b591c9b22f4ecced14675fe5e5334\">\n\n  \n  <div class=\"wpv-resources\"><a name=\"video\" class=\"video-anchor\"><\/a>\n    <div id=\"ult-carousel-20544561746a985bc85550e\" class=\"ult-carousel-wrapper  vc-el-carousel-videos-embedded ult_horizontal\" data-gutter=\"0\" data-rtl=\"false\" ><div class=\"ult-carousel-19458039516a985bc8554e6 \" >\n    \n    \n       <div><!-- slide container -->\n        <div class=\"wpv-resources-item\" data-mh=\".wpv-resources-item\">\n          <div class=\"resources-item-poster\">\n              <div id=\"wpfp_0463c315c6fe8e73511efd67ca4b8a8a\" data-item=\"{&quot;sources&quot;:&#091;{&quot;src&quot;:&quot;https:\\\/\\\/media.plm.automation.siemens.com\\\/solidedge\\\/SE-Design-Mobility-44414.mp4&quot;,&quot;type&quot;:&quot;video\\\/mp4&quot;}&#093;}\" class=\"flowplayer no-brand is-splash no-svg is-paused skin-slim fp-slim fp-edgy\" data-embed=\"false\" style=\"max-width: 1140px; max-height: 640px; background-image: url(https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2018\/04\/v-design-mobility.jpg);\" data-ratio=\"0.5614\" data-advance=\"false\">\n\t<div class=\"fp-ratio\" style=\"padding-top: 56.14%\"><\/div>\n\t<div class=\"fp-ui\"><div class=\"fp-play fp-visible\"><a class=\"fp-icon fp-playbtn\"><\/a><\/div><\/div>\n\n<\/div>\n\n              \n          <\/div>\n        <\/div>\n      <\/div>\n    \n    \n    <\/div><\/div>\t\t\t<script type=\"text\/javascript\">\r\n\t\t\t\tjQuery(document).ready(function ($) {\r\n\t\t\t\t\tif( typeof jQuery('.ult-carousel-19458039516a985bc8554e6').slick == \"function\"){\r\n\t\t\t\t\t\t$('.ult-carousel-19458039516a985bc8554e6').slick({dots: true,autoplaySpeed: 5000,speed: 500,infinite: false,arrows: true,nextArrow: '<button type=\"button\" role=\"button\" aria-label=\"Next\" style=\"color:#ffffff; font-size:30px;background:rgba(47,56,60,0.5);\" class=\"slick-next square-bg\"><i class=\"ultsl-arrow-right6\"><\/i><\/button>',prevArrow: '<button type=\"button\" role=\"button\" aria-label=\"Previous\" style=\"color:#ffffff; font-size:30px;background:rgba(47,56,60,0.5);\" class=\"slick-prev square-bg\"><i class=\"ultsl-arrow-left6\"><\/i><\/button>',slidesToScroll:1,slidesToShow:1,swipe: true,draggable: true,touchMove: true,pauseOnHover: true,pauseOnFocus: false,responsive: [\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t  breakpoint: 1026,\r\n\t\t\t\t\t\t\t  settings: {\r\n\t\t\t\t\t\t\t\tslidesToShow: 1,\r\n\t\t\t\t\t\t\t\tslidesToScroll: 1,  \r\n\t\t\t\t\t\t\t  }\r\n\t\t\t\t\t\t\t},\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t  breakpoint: 1025,\r\n\t\t\t\t\t\t\t  settings: {\r\n\t\t\t\t\t\t\t\tslidesToShow: 1,\r\n\t\t\t\t\t\t\t\tslidesToScroll: 1\r\n\t\t\t\t\t\t\t  }\r\n\t\t\t\t\t\t\t},\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t  breakpoint: 760,\r\n\t\t\t\t\t\t\t  settings: {\r\n\t\t\t\t\t\t\t\tslidesToShow: 1,\r\n\t\t\t\t\t\t\t\tslidesToScroll: 1\r\n\t\t\t\t\t\t\t  }\r\n\t\t\t\t\t\t\t}\r\n\t\t\t\t\t\t],pauseOnDotsHover: true,customPaging: function(slider, i) {\r\n                   return '<i type=\"button\" style= \"color:#788891;\" class=\"ultsl-record\" data-role=\"none\"><\/i>';\r\n                },});\r\n\t\t\t\t\t}\r\n\t\t\t\t});\r\n\t\t\t<\/script>\r\n\t\t\t\n  <\/div>\n  \n  \n  <\/div>\n[vc_column_text el_class=&#8220;video-caption&#8220;]Mit Solid Edge k&ouml;nnen Benutzern praktisch &uuml;berall mit einer Konstruktion beginnen, einen virtuellen Prototyp erstellen und das neue Teil genau dann fertigstellen, wenn es ben&ouml;tigt wird. Durch die schnellere Konstruktion k&ouml;nnen Sie sich dank Solid Edge frei f&uuml;r eine &Auml;nderung entscheiden, w&auml;hrend Ihnen bisher m&ouml;glicherweise nicht genug Zeit daf&uuml;r blieb. Somit bedeutet Schnelligkeit bei der Konstruktion auch Schnelligkeit bei der Fertigung und Lieferung.[\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=&#8220;stretch_row&#8220; el_class=&#8220;vc-row-shoutbox&#8220; css=&#8220;.vc_custom_1524241646732{background-color: #003750 !important;}&#8220;][vc_column width=&#8220;1\/3&#8243;][vc_single_image image=&#8220;1074&#8243; img_size=&#8220;full&#8220; alignment=&#8220;center&#8220;][\/vc_column][vc_column width=&#8220;2\/3&#8243;][vc_column_text el_class=&#8220;vc-el-lead-in&#8220;]ROI-Berechnung<\/p>\n<h2>Finden Sie Ihren ROI mit Solid Edge<\/h2>\n<p>Wie k&ouml;nnen Sie durch einen Paradigmenwechsel beim Modellieren Zeit und Geld sparen? Dieser Rechner simuliert den potenziellen ROI, den Sie mithilfe von Synchronous Technology in Solid Edge erzielen k&ouml;nnten.<\/p>\n<p><a class=\"action-button\" href=\"https:\/\/solidedge.siemens.com\/de\/roi-calculator\/\"><i class=\"icon-ext\"><\/i>Jetzt starten<\/a>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text el_class=&#8220;vc-el-lead-in&#8220;]Highlights<\/p>\n<h2>Solid Edge-Funktionen<\/h2>\n<p>Wie stellt Solid Edge alles bereit, was Konstrukteure und Ingenieure ben&ouml;tigen, um die Produktentwicklung zu beschleunigen, Revisionen schneller durchzuf&uuml;hren und die Wiederverwendung von Konstruktionsdaten zu verbessern? Von den Kernfunktionen der Modellierung bis zur Konstruktionsfunktionalit&auml;t der n&auml;chsten Generation &ndash; Solid Edge hat alles, was Sie ben&ouml;tigen, um schnell loszulegen. [\/vc_column_text][vc_row_inner equal_height=&#8220;yes&#8220; el_class=&#8220;vc-row-image-teasers&#8220;][vc_column_inner width=&#8220;1\/3&#8243;][vc_column_text]<\/p>\n<h3><a href=\"https:\/\/solidedge.siemens.com\/de\/solutions\/products\/3d-design\/next-generation-design\/\">Konstruktion der n&auml;chsten Generation<\/a><\/h3>\n<p>Die Zukunft der 3D-Produktentwicklung &ndash; generative Modellierung, additive Fertigung und Reverse Engineering, erm&ouml;glicht durch Convergent Modeling-Technologie.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8220;1\/3&#8243;][vc_column_text]<\/p>\n<h3><a href=\"https:\/\/solidedge.siemens.com\/de\/solutions\/products\/3d-design\/synchronous-technology\/\">Synchronous Technology<\/a><\/h3>\n<p>Kombination der Geschwindigkeit und Einfachheit der Direktmodellierung mit der Flexibilit&auml;t und den Steuerungsm&ouml;glichkeiten der parametrischen Konstruktion.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8220;1\/3&#8243;][vc_column_text]<\/p>\n<h3><a href=\"https:\/\/solidedge.siemens.com\/de\/solutions\/products\/3d-design\/sheet-metal-design\/\">Blechkonstruktion<\/a><\/h3>\n<p>Ein vollst&auml;ndiges System f&uuml;r die Blechkonstruktion mit unterst&uuml;tzenden Funktionen f&uuml;r den gesamten Konstruktions- und Fertigungsprozess.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8220;1\/3&#8243;][vc_column_text]<\/p>\n<h3><a href=\"https:\/\/solidedge.siemens.com\/de\/solutions\/products\/3d-design\/assembly-modeling-and-management-archived\/\">Baugruppenmodellierung und -verwaltung<\/a><\/h3>\n<p>Herausragende Baugruppenperformance: egal, ob Sie mit ein paar wenigen Komponenten hantieren oder mit Hunderten bzw. Tausenden von Teilen arbeiten.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8220;1\/3&#8243;][vc_column_text]<\/p>\n<h3><a href=\"https:\/\/solidedge.siemens.com\/de\/solutions\/products\/3d-design\/cad-drawing-and-drafting\/\">CAD-Zeichnungen und -Entw&uuml;rfe<\/a><\/h3>\n<p>Steuerungen f&uuml;r Zeichnungslayout, Detaillierung, Anmerkungen und Bema&szlig;ung, die automatisch die Standards f&uuml;r mechanische Entw&uuml;rfe einhalten.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8220;1\/3&#8243;][vc_column_text]<\/p>\n<h3><a href=\"https:\/\/solidedge.siemens.com\/de\/solutions\/products\/3d-design\/industrial-design-software\/3d-rendering\/\">Fotorealistische Darstellung<\/a><\/h3>\n<p>Fotorealistische Bilder und Animationen aus der Modellierungsumgebung, um Ihre Modelle zum Leben zu erwecken. [\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8220;1\/3&#8243;][vc_column_text]<\/p>\n<h3><a href=\"https:\/\/solidedge.siemens.com\/de\/solutions\/products\/3d-design\/cloud-enabled-design\/\">Cloudf&auml;hige Konstruktion<\/a><\/h3>\n<p>Einfacher Zugriff von mehreren Ger&auml;ten, sofortige Konfiguration Ihrer CAD-Umgebung und schnelle Datenfreigabe f&uuml;r Teammitglieder, Lieferanten und Kunden.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=&#8220;stretch_row&#8220; el_class=&#8220;vc-row-testimonial-quote&#8220; css=&#8220;.vc_custom_1525135482098{background-color: #13374e !important;}&#8220;][vc_column offset=&#8220;vc_col-lg-offset-1 vc_col-lg-10&#8243;][vc_column_text el_class=&#8220;vc-el-testimonial-quote&#8220;]Alles, was ich konstruiere, sollte am besten schon gestern fertig sein.<\/p>\n<p style=\"text-align: right;\"><cite>Jan van der Tol, Konstrukteur und Teamchef von Ten Kate Racing<\/cite><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row equal_height=&#8220;yes&#8220; el_class=&#8220;vc-row-subnavigation-links&#8220;][vc_column width=&#8220;3\/3&#8243;][vc_column_text]Funktionen<\/p>\n<h2>Weitere Informationen zum Solid Edge-Portfolio<\/h2>\n<p>Solid Edge bietet Anwendern ein umfassendes Portfolio mit L&ouml;sungen, mit denen sich die unterschiedlichsten gesch&auml;ftlichen Anforderungen erf&uuml;llen lassen. Solid Edge bietet nicht nur umfangreiche Konstruktionsl&ouml;sungen, sondern auch skalierbare L&ouml;sungen f&uuml;r Simulation, Fertigung und Daten-Management.[\/vc_column_text][vc_row_inner][vc_column_inner width=&#8220;1\/2&#8243;][vc_column_text]<a href=\"https:\/\/solidedge.siemens.com\/de\/solutions\/products\/3d-design\/next-generation-design\/\">Geschwindigkeit, Flexibilit&auml;t und Konstruktion der n&auml;chsten Generation<\/a>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8220;1\/2&#8243;][vc_column_text]<a href=\"https:\/\/solidedge.siemens.com\/de\/solutions\/products\/simulation\/\">Integrierte elektrische Konstruktion<\/a>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8220;1\/2&#8243;][vc_column_text]<a href=\"https:\/\/solidedge.siemens.com\/de\/solutions\/products\/simulation\/\">Skalierbare Simulationssoftware steuert die Konstruktion<\/a>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8220;1\/2&#8243;][vc_column_text]<a href=\"https:\/\/solidedge.siemens.com\/de\/solutions\/products\/data-management\/\">Skalierbares Daten-Management<\/a>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8220;1\/2&#8243;][vc_column_text]<a href=\"https:\/\/solidedge.siemens.com\/de\/solutions\/products\/computer-aided-manufacturing-cam\/\">Herk&ouml;mmliche und additive Fertigung<\/a>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8220;1\/2&#8243;][vc_column_text]<a href=\"https:\/\/solidedge.siemens.com\/de\/solutions\/products\/technical-publications\/\">Dynamische technische Publikationen<\/a>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8220;1\/2&#8243;][vc_column_text]<a href=\"https:\/\/solidedge.siemens.com\/de\/solutions\/products\/3d-design\/cloud-enabled-design\/\">Zusammenarbeit in der Cloud<\/a>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8220;1\/2&#8243;][vc_column_text]<a href=\"https:\/\/solidedge.siemens.com\/de\/solutions\/products\/complete-product-development-portfolio\/\">Vollst&auml;ndiges Solid Edge-Portfolio sehen<\/a>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=&#8220;stretch_row&#8220; el_class=&#8220;vc-row-free-software&#8220; css=&#8220;.vc_custom_1523912493378{background-color: #006486 !important;}&#8220;][vc_column][vc_column_text el_class=&#8220;vc-el-lead-in&#8220;]ANGEBOTE<\/p>\n<h2>3D-Konstruktionssoftware<\/h2>\n<p>[\/vc_column_text][vc_row_inner equal_height=&#8220;yes&#8220;][vc_column_inner width=&#8220;1\/2&#8243; offset=&#8220;vc_col-md-5&#8243;]<div class=\"wpb_content_block wpb_content_element\"><div class=\"wpb_wrapper\"><div class=\"content_block\" id=\"custom_post_widget-1194\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<h3>Besuchen Sie unseren Online-Store<\/h3>\n<p>Registrieren Sie sich f\u00fcr unsere kostenlose Testversion, sehen Sie sich aktuelle Angebote an, vergleichen Sie Produktpakete und erwerben Sie Monats- oder Jahresabonnements.[\/vc_column_text][vc_column_text]<a class=\"action-button\" href=\"\/de\/buy-now\/\">Jetzt besuchen<\/a>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div><\/div><\/div>[\/vc_column_inner][vc_column_inner width=&#8220;1\/2&#8243; offset=&#8220;vc_col-md-offset-2 vc_col-md-5&#8243;]<div class=\"wpb_content_block wpb_content_element\"><div class=\"wpb_wrapper\"><div class=\"content_block\" id=\"custom_post_widget-419\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<h3>Kostenlose Software f\u00fcr Ihr Start-up<\/h3>\n<p>Wenn Sie ein junges, d.\u00a0h. ein vor weniger als drei Jahren gegr\u00fcndetes Start-up-Unternehmen f\u00fchren, k\u00f6nnen Sie sich jetzt f\u00fcr ein kostenloses Solid Edge-Jahresabo bewerben. Ohne Anmeldegeb\u00fchr![\/vc_column_text][vc_column_text]<a class=\"action-button\" href=\"https:\/\/www.plm.automation.siemens.com\/global\/de\/topic\/solid-edge-for-startups\/8335\"><i class=\"icon-ext\"><\/i>Jetzt bewerben<\/a>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div><\/div><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=&#8220;stretch_row&#8220; el_class=&#8220;vc-row-customer-stories&#8220;][vc_column][vc_column_text el_class=&#8220;vc-el-lead-in&#8220;]Kundenberichte<\/p>\n<h2>Wie Unternehmen durch 3D-Konstruktion Vorteile erzielen<\/h2>\n<p>[\/vc_column_text]\n\n\n<div id=\"wpv-view-layout-570-CATTR781a3d0b8fad0b223932194fcc67a6a9\" class=\"js-wpv-view-layout js-wpv-layout-responsive js-wpv-view-layout-570-CATTR781a3d0b8fad0b223932194fcc67a6a9\" data-viewnumber=\"570-CATTR781a3d0b8fad0b223932194fcc67a6a9\" data-pagination=\"{&quot;id&quot;:570,&quot;query&quot;:&quot;normal&quot;,&quot;type&quot;:&quot;disabled&quot;,&quot;effect&quot;:&quot;fade&quot;,&quot;duration&quot;:500,&quot;speed&quot;:5,&quot;pause_on_hover&quot;:&quot;disabled&quot;,&quot;stop_rollover&quot;:&quot;false&quot;,&quot;cache_pages&quot;:&quot;enabled&quot;,&quot;preload_images&quot;:&quot;enabled&quot;,&quot;preload_pages&quot;:&quot;enabled&quot;,&quot;preload_reach&quot;:1,&quot;spinner&quot;:&quot;builtin&quot;,&quot;spinner_image&quot;:&quot;https:\/\/solidedge.siemens.com\/wp-content\/plugins\/wp-views\/embedded\/res\/img\/ajax-loader.gif&quot;,&quot;callback_next&quot;:&quot;&quot;,&quot;manage_history&quot;:&quot;disabled&quot;,&quot;has_controls_in_form&quot;:&quot;disabled&quot;,&quot;infinite_tolerance&quot;:&quot;0&quot;,&quot;max_pages&quot;:0,&quot;page&quot;:1,&quot;base_permalink&quot;:&quot;\/de\/wp-json\/wp\/v2\/pages\/2555?wpv_view_count=570-CATTR781a3d0b8fad0b223932194fcc67a6a9&amp;wpv_paged=WPV_PAGE_NUM&quot;,&quot;loop&quot;:{&quot;type&quot;:&quot;&quot;,&quot;name&quot;:&quot;&quot;,&quot;data&quot;:[],&quot;id&quot;:0}}\" data-permalink=\"\/de\/wp-json\/wp\/v2\/pages\/2555?wpv_view_count=570-CATTR781a3d0b8fad0b223932194fcc67a6a9\">\n\n\t\n    <div class=\"wpv-resources\">\n      <p class=\"see-more\"><a href=\"https:\/\/www.plm.automation.siemens.com\/global\/en\/our-story\/customers\/#\/?productKeywords=solidEdge\">See More Stories<\/a><\/p>\n      <div id=\"ult-carousel-21191966246a985bc899400\" class=\"ult-carousel-wrapper  vc-el-carousel-customer-stories ult_horizontal\" data-gutter=\"0\" data-rtl=\"false\" ><div class=\"ult-carousel-20804120186a985bc8993dd \" >\n      \n      \n        <div><!-- slide container -->\n          <div class=\"wpv-resources-item\" data-mh=\".wpv-resources-item\">\n            <div class=\"resources-item-poster\"><a href=\"https:\/\/solidedge.siemens.com\/de\/customer-story\/theebo-tech-design-speed\/\" title=\"Read the Customer Story\"><img src=\"https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2018\/04\/v-theebo-480x270.jpg\" alt=\"Theebo Tech\" class=\"attachment-resources-poster size-resources-poster wp-post-image\" \/><\/a>\n            <\/div>\n            <div class=\"resources-item-content\">\n              <p class=\"resources-item-meta\">Theebo Tech | South Africa<\/p>\n              <p class=\"resources-item-title\">Agricultural equipment manufacturer speeds up product design with Solid Edge<\/p>\n              <p class=\"resources-item-read-more\"><a href=\"https:\/\/solidedge.siemens.com\/de\/customer-story\/theebo-tech-design-speed\/\" title=\"Read the Customer Story\"><i class=\"icon-ext\"><\/i>Read the Customer Story<\/a><\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n      \n        <div><!-- slide container -->\n          <div class=\"wpv-resources-item\" data-mh=\".wpv-resources-item\">\n            <div class=\"resources-item-poster\"><a href=\"https:\/\/solidedge.siemens.com\/de\/customer-story\/pyga\/\" title=\"Read the Customer Story\"><img src=\"https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2018\/04\/c-pyga.jpg\" alt=\"Pyga\" class=\"attachment-resources-poster size-resources-poster wp-post-image\" \/><\/a>\n            <\/div>\n            <div class=\"resources-item-content\">\n              <p class=\"resources-item-meta\">Pyga | South Africa<\/p>\n              <p class=\"resources-item-title\">Pyga Industries improves performance and reduces time-to-market with Solid Edge<\/p>\n              <p class=\"resources-item-read-more\"><a href=\"https:\/\/solidedge.siemens.com\/de\/customer-story\/pyga\/\" title=\"Read the Customer Story\"><i class=\"icon-ext\"><\/i>Read the Customer Story<\/a><\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n      \n        <div><!-- slide container -->\n          <div class=\"wpv-resources-item\" data-mh=\".wpv-resources-item\">\n            <div class=\"resources-item-poster\"><a href=\"https:\/\/solidedge.siemens.com\/de\/customer-story\/wkidea\/\" title=\"Read the Customer Story\"><img src=\"https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2018\/04\/c-wkidea.jpg\" alt=\"Wkidea\" class=\"attachment-resources-poster size-resources-poster wp-post-image\" \/><\/a>\n            <\/div>\n            <div class=\"resources-item-content\">\n              <p class=\"resources-item-meta\">Wkidea | Taiwan<\/p>\n              <p class=\"resources-item-title\">Integrated design-through-manufacturing system delivers a custom wooden cell phone case in just three hours; also opens door to new markets<\/p>\n              <p class=\"resources-item-read-more\"><a href=\"https:\/\/solidedge.siemens.com\/de\/customer-story\/wkidea\/\" title=\"Read the Customer Story\"><i class=\"icon-ext\"><\/i>Read the Customer Story<\/a><\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n      \n        <div><!-- slide container -->\n          <div class=\"wpv-resources-item\" data-mh=\".wpv-resources-item\">\n            <div class=\"resources-item-poster\"><a href=\"https:\/\/solidedge.siemens.com\/de\/customer-story\/isono-body\/\" title=\"Read the Customer Story\"><img src=\"https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2018\/04\/c-isono-body.jpg\" alt=\"Isono Body\" class=\"attachment-resources-poster size-resources-poster wp-post-image\" \/><\/a>\n            <\/div>\n            <div class=\"resources-item-content\">\n              <p class=\"resources-item-meta\">Isono Body | Japan<\/p>\n              <p class=\"resources-item-title\">Dramatic improvements in product development using Solid Edge and MACsheet SEG5<\/p>\n              <p class=\"resources-item-read-more\"><a href=\"https:\/\/solidedge.siemens.com\/de\/customer-story\/isono-body\/\" title=\"Read the Customer Story\"><i class=\"icon-ext\"><\/i>Read the Customer Story<\/a><\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n      \n        <div><!-- slide container -->\n          <div class=\"wpv-resources-item\" data-mh=\".wpv-resources-item\">\n            <div class=\"resources-item-poster\"><a href=\"https:\/\/solidedge.siemens.com\/de\/customer-story\/goster\/\" title=\"Read the Customer Story\"><img src=\"https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2018\/04\/c-goster.jpg\" alt=\"Goster\" class=\"attachment-resources-poster size-resources-poster wp-post-image\" \/><\/a>\n            <\/div>\n            <div class=\"resources-item-content\">\n              <p class=\"resources-item-meta\">Goster | Poland<\/p>\n              <p class=\"resources-item-title\">Economic downturn drives change in strategy<\/p>\n              <p class=\"resources-item-read-more\"><a href=\"https:\/\/solidedge.siemens.com\/de\/customer-story\/goster\/\" title=\"Read the Customer Story\"><i class=\"icon-ext\"><\/i>Read the Customer Story<\/a><\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n      \n        <div><!-- slide container -->\n          <div class=\"wpv-resources-item\" data-mh=\".wpv-resources-item\">\n            <div class=\"resources-item-poster\"><a href=\"https:\/\/solidedge.siemens.com\/de\/customer-story\/kaspar-schulz\/\" title=\"Read the Customer Story\"><img src=\"https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2018\/04\/c-kaspar-schulz.jpg\" alt=\"Kaspar Schulz\" class=\"attachment-resources-poster size-resources-poster wp-post-image\" \/><\/a>\n            <\/div>\n            <div class=\"resources-item-content\">\n              <p class=\"resources-item-meta\">Kaspar Schulz | Germany<\/p>\n              <p class=\"resources-item-title\">Integration of project planning, pipe routing and 3D design<\/p>\n              <p class=\"resources-item-read-more\"><a href=\"https:\/\/solidedge.siemens.com\/de\/customer-story\/kaspar-schulz\/\" title=\"Read the Customer Story\"><i class=\"icon-ext\"><\/i>Read the Customer Story<\/a><\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n      \n        <div><!-- slide container -->\n          <div class=\"wpv-resources-item\" data-mh=\".wpv-resources-item\">\n            <div class=\"resources-item-poster\"><a href=\"https:\/\/solidedge.siemens.com\/de\/customer-story\/trlby\/\" title=\"Read the Customer Story\"><img src=\"https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2018\/04\/c-trlby.jpg\" alt=\"Trlby\" class=\"attachment-resources-poster size-resources-poster wp-post-image\" \/><\/a>\n            <\/div>\n            <div class=\"resources-item-content\">\n              <p class=\"resources-item-meta\">Trlby | USA<\/p>\n              <p class=\"resources-item-title\">Solid Edge selected over SolidWorks and Inventor<\/p>\n              <p class=\"resources-item-read-more\"><a href=\"https:\/\/solidedge.siemens.com\/de\/customer-story\/trlby\/\" title=\"Read the Customer Story\"><i class=\"icon-ext\"><\/i>Read the Customer Story<\/a><\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n      \n        <div><!-- slide container -->\n          <div class=\"wpv-resources-item\" data-mh=\".wpv-resources-item\">\n            <div class=\"resources-item-poster\"><a href=\"https:\/\/solidedge.siemens.com\/de\/customer-story\/hydrauvision\/\" title=\"Read the Customer Story\"><img src=\"https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2019\/02\/Hydrauvision-480x270.jpg\" alt=\"Hydrauvision\" class=\"attachment-resources-poster size-resources-poster wp-post-image\" \/><\/a>\n            <\/div>\n            <div class=\"resources-item-content\">\n              <p class=\"resources-item-meta\">Hydrauvision<\/p>\n              <p class=\"resources-item-title\">Hydraulic power manufacturer cuts down reliance on prototypes<\/p>\n              <p class=\"resources-item-read-more\"><a href=\"https:\/\/solidedge.siemens.com\/de\/customer-story\/hydrauvision\/\" title=\"Read the Customer Story\"><i class=\"icon-ext\"><\/i>Read the Customer Story<\/a><\/p>\n            <\/div>\n          <\/div>\n        <\/div>\n      \n      \n      <\/div><\/div>\t\t\t<script type=\"text\/javascript\">\r\n\t\t\t\tjQuery(document).ready(function ($) {\r\n\t\t\t\t\tif( typeof jQuery('.ult-carousel-20804120186a985bc8993dd').slick == \"function\"){\r\n\t\t\t\t\t\t$('.ult-carousel-20804120186a985bc8993dd').slick({dots: true,autoplaySpeed: 5000,speed: 500,infinite: false,arrows: true,nextArrow: '<button type=\"button\" role=\"button\" aria-label=\"Next\" style=\"color:#ffffff; font-size:30px;background:rgba(47,56,60,0.5);\" class=\"slick-next square-bg\"><i class=\"ultsl-arrow-right6\"><\/i><\/button>',prevArrow: '<button type=\"button\" role=\"button\" aria-label=\"Previous\" style=\"color:#ffffff; font-size:30px;background:rgba(47,56,60,0.5);\" class=\"slick-prev square-bg\"><i class=\"ultsl-arrow-left6\"><\/i><\/button>',slidesToScroll:3,slidesToShow:3,swipe: true,draggable: true,touchMove: true,pauseOnHover: true,pauseOnFocus: false,responsive: [\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t  breakpoint: 1026,\r\n\t\t\t\t\t\t\t  settings: {\r\n\t\t\t\t\t\t\t\tslidesToShow: 3,\r\n\t\t\t\t\t\t\t\tslidesToScroll: 3,  \r\n\t\t\t\t\t\t\t  }\r\n\t\t\t\t\t\t\t},\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t  breakpoint: 1025,\r\n\t\t\t\t\t\t\t  settings: {\r\n\t\t\t\t\t\t\t\tslidesToShow: 2,\r\n\t\t\t\t\t\t\t\tslidesToScroll: 2\r\n\t\t\t\t\t\t\t  }\r\n\t\t\t\t\t\t\t},\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t  breakpoint: 760,\r\n\t\t\t\t\t\t\t  settings: {\r\n\t\t\t\t\t\t\t\tslidesToShow: 1,\r\n\t\t\t\t\t\t\t\tslidesToScroll: 1\r\n\t\t\t\t\t\t\t  }\r\n\t\t\t\t\t\t\t}\r\n\t\t\t\t\t\t],pauseOnDotsHover: true,customPaging: function(slider, i) {\r\n                   return '<i type=\"button\" style= \"color:#788891;\" class=\"ultsl-record\" data-role=\"none\"><\/i>';\r\n                },});\r\n\t\t\t\t\t}\r\n\t\t\t\t});\r\n\t\t\t<\/script>\r\n\t\t\t\n\t<\/div>\n\t\n\t\n<\/div>\n[\/vc_column][\/vc_row][vc_row full_width=&#8220;stretch_row&#8220; el_class=&#8220;vc-row-related-content&#8220; css=&#8220;.vc_custom_1524184785822{background-color: #347eb5 !important;}&#8220;][vc_column][vc_column_text]<\/p>\n<h2>&Auml;hnliche Inhalte<\/h2>\n<p>[\/vc_column_text]<div id=\"ult-carousel-13264058616a985bc89992d\" class=\"ult-carousel-wrapper  vc-el-carousel-related-content ult_horizontal\" data-gutter=\"0\" data-rtl=\"false\" ><div class=\"ult-carousel-15188472806a985bc89990c \" >[vc_column_text]<a href=\"https:\/\/www.plm.automation.siemens.com\/en_us\/Images\/D3D-Siemens-SolidEdge-2015_tcm1023-243894.pdf\">Blick in die Fachmedien:<br \/>\nWarum ist Solid Edge besser?<\/a>[\/vc_column_text][vc_column_text]<a href=\"https:\/\/www.plm.automation.siemens.com\/global\/en\/topic\/cad-design-challenges-infographic\/2496\">Infografik:<br \/>\nHerausforderungen bei der Konstruktion<\/a>[\/vc_column_text][vc_column_text]<a href=\"https:\/\/solidedge.siemens.com\/de\/roi-calculator\/\">Der ROI von Solid Edge<\/a>[\/vc_column_text][vc_column_text]<a href=\"https:\/\/solidedge.siemens.com\/de\/solutions\/products\/complete-product-development-portfolio\/whats-new-in-solid-edge-2019\/\">Solid Edge 2019<\/a>[\/vc_column_text][vc_column_text]<a href=\"http:\/\/community.plm.automation.siemens.com\/t5\/Solid-Edge\/ct-p\/solid-edge\">Solid Edge Community<\/a>[\/vc_column_text][vc_column_text]<a href=\"http:\/\/www.facebook.com\/solidedge\">Solid Edge auf Facebook<\/a>[\/vc_column_text][vc_column_text]<a href=\"https:\/\/www.youtube.com\/user\/SiemensPLM\/playlists?shelf_id=18&amp;view=50&amp;sort=dd\">Solid Edge auf YouTube<\/a>[\/vc_column_text]<\/div><\/div>\t\t\t<script type=\"text\/javascript\">\r\n\t\t\t\tjQuery(document).ready(function ($) {\r\n\t\t\t\t\tif( typeof jQuery('.ult-carousel-15188472806a985bc89990c').slick == \"function\"){\r\n\t\t\t\t\t\t$('.ult-carousel-15188472806a985bc89990c').slick({dots: true,autoplaySpeed: 5000,speed: 500,infinite: false,arrows: true,nextArrow: '<button type=\"button\" role=\"button\" aria-label=\"Next\" style=\"color:#ffffff; font-size:30px;background:rgba(255,255,255,0.2);\" class=\"slick-next square-bg\"><i class=\"ultsl-arrow-right6\"><\/i><\/button>',prevArrow: '<button type=\"button\" role=\"button\" aria-label=\"Previous\" style=\"color:#ffffff; font-size:30px;background:rgba(255,255,255,0.2);\" class=\"slick-prev square-bg\"><i class=\"ultsl-arrow-left6\"><\/i><\/button>',slidesToScroll:4,slidesToShow:4,swipe: true,draggable: true,touchMove: true,pauseOnHover: true,pauseOnFocus: false,responsive: [\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t  breakpoint: 1026,\r\n\t\t\t\t\t\t\t  settings: {\r\n\t\t\t\t\t\t\t\tslidesToShow: 4,\r\n\t\t\t\t\t\t\t\tslidesToScroll: 4,  \r\n\t\t\t\t\t\t\t  }\r\n\t\t\t\t\t\t\t},\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t  breakpoint: 1025,\r\n\t\t\t\t\t\t\t  settings: {\r\n\t\t\t\t\t\t\t\tslidesToShow: 2,\r\n\t\t\t\t\t\t\t\tslidesToScroll: 2\r\n\t\t\t\t\t\t\t  }\r\n\t\t\t\t\t\t\t},\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t  breakpoint: 760,\r\n\t\t\t\t\t\t\t  settings: {\r\n\t\t\t\t\t\t\t\tslidesToShow: 1,\r\n\t\t\t\t\t\t\t\tslidesToScroll: 1\r\n\t\t\t\t\t\t\t  }\r\n\t\t\t\t\t\t\t}\r\n\t\t\t\t\t\t],pauseOnDotsHover: true,customPaging: function(slider, i) {\r\n                   return '<i type=\"button\" style= \"color:#ffffff;\" class=\"ultsl-record\" data-role=\"none\"><\/i>';\r\n                },});\r\n\t\t\t\t\t}\r\n\t\t\t\t});\r\n\t\t\t<\/script>\r\n\t\t\t[\/vc_column][\/vc_row][vc_row full_width=&#8220;stretch_row&#8220; el_class=&#8220;footer-contact&#8220; css=&#8220;.vc_custom_1550170708528{background-color: #dedee3 !important;}&#8220;][vc_column]<div class=\"wpb_content_block wpb_content_element\"><div class=\"wpb_wrapper\"><\/div><\/div>[\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p> Rennen gewinnen durch besseres CAD Solid Edge f&ouml;rdert Innovationen und bietet grenzenlose Konstruktionsfreiheit. Synchronous Technology hilft Ihnen, schneller und intelligenter zu konstruieren, und eliminiert zugleich die Beschr&auml;nkungen der herk&ouml;mmlichen 3D-Modellierung. Mit Solid Edge bekommen Sie eine voll funktionale L&ouml;sung [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":2774,"menu_order":3,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.4.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Konstrukteure und Ingenieure | 3D-CAD | Solid Edge<\/title>\n<meta name=\"description\" content=\"Solid Edge hat die Antwort f\u00fcr Konstrukteure und Ingenieure. Erleben Sie in diesem Video hautnah, wie die schnellen, flexiblen CAD-Konstruktionsfunktionen Konzepte in Windeseile zum Leben erwecken.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/solidedge.siemens.com\/de\/solutions\/products\/complete-product-development-portfolio\/designers-and-engineers\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Konstrukteure und Ingenieure | 3D-CAD | Solid Edge\" \/>\n<meta property=\"og:description\" content=\"Solid Edge hat die Antwort f\u00fcr Konstrukteure und Ingenieure. Erleben Sie in diesem Video hautnah, wie die schnellen, flexiblen CAD-Konstruktionsfunktionen Konzepte in Windeseile zum Leben erwecken.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/solidedge.siemens.com\/de\/solutions\/products\/complete-product-development-portfolio\/designers-and-engineers\/\" \/>\n<meta property=\"og:site_name\" content=\"Solid Edge\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/solidedge\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-20T19:19:12+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@siemensplm\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/solidedge.siemens.com\/en\/#organization\",\"name\":\"Siemens Digital Industries Software\",\"url\":\"https:\/\/solidedge.siemens.com\/en\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/solidedge\",\"https:\/\/www.instagram.com\/siemens\/\",\"https:\/\/www.linkedin.com\/company\/siemens-plm-software\",\"https:\/\/www.youtube.com\/user\/PolarionSoftware\",\"https:\/\/twitter.com\/siemensplm\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/solidedge.siemens.com\/en\/#logo\",\"inLanguage\":\"de-DE\",\"url\":\"https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2018\/04\/logo-siemens-ifl@2x.png\",\"contentUrl\":\"https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2018\/04\/logo-siemens-ifl@2x.png\",\"width\":640,\"height\":270,\"caption\":\"Siemens Digital Industries Software\"},\"image\":{\"@id\":\"https:\/\/solidedge.siemens.com\/en\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/solidedge.siemens.com\/en\/#website\",\"url\":\"https:\/\/solidedge.siemens.com\/en\/\",\"name\":\"Solid Edge\",\"description\":\"Siemens Software\",\"publisher\":{\"@id\":\"https:\/\/solidedge.siemens.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/solidedge.siemens.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/solidedge.siemens.com\/de\/solutions\/products\/complete-product-development-portfolio\/designers-and-engineers\/#webpage\",\"url\":\"https:\/\/solidedge.siemens.com\/de\/solutions\/products\/complete-product-development-portfolio\/designers-and-engineers\/\",\"name\":\"Konstrukteure und Ingenieure | 3D-CAD | Solid Edge\",\"isPartOf\":{\"@id\":\"https:\/\/solidedge.siemens.com\/en\/#website\"},\"datePublished\":\"2019-04-01T14:22:21+00:00\",\"dateModified\":\"2021-04-20T19:19:12+00:00\",\"description\":\"Solid Edge hat die Antwort f\u00fcr Konstrukteure und Ingenieure. Erleben Sie in diesem Video hautnah, wie die schnellen, flexiblen CAD-Konstruktionsfunktionen Konzepte in Windeseile zum Leben erwecken.\",\"breadcrumb\":{\"@id\":\"https:\/\/solidedge.siemens.com\/de\/solutions\/products\/complete-product-development-portfolio\/designers-and-engineers\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/solidedge.siemens.com\/de\/solutions\/products\/complete-product-development-portfolio\/designers-and-engineers\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/solidedge.siemens.com\/de\/solutions\/products\/complete-product-development-portfolio\/designers-and-engineers\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/solidedge.siemens.com\/en\/home-7\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&ouml;sungen\",\"item\":\"https:\/\/solidedge.siemens.com\/de\/solutions\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Produkte\",\"item\":\"https:\/\/solidedge.siemens.com\/de\/solutions\/products\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Vollst&auml;ndiges Produktentwicklungsportfolio\",\"item\":\"https:\/\/solidedge.siemens.com\/de\/solutions\/products\/complete-product-development-portfolio\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Konstrukteure und Ingenieure\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Konstrukteure und Ingenieure | 3D-CAD | Solid Edge","description":"Solid Edge hat die Antwort f\u00fcr Konstrukteure und Ingenieure. Erleben Sie in diesem Video hautnah, wie die schnellen, flexiblen CAD-Konstruktionsfunktionen Konzepte in Windeseile zum Leben erwecken.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/solidedge.siemens.com\/de\/solutions\/products\/complete-product-development-portfolio\/designers-and-engineers\/","og_locale":"de_DE","og_type":"article","og_title":"Konstrukteure und Ingenieure | 3D-CAD | Solid Edge","og_description":"Solid Edge hat die Antwort f\u00fcr Konstrukteure und Ingenieure. Erleben Sie in diesem Video hautnah, wie die schnellen, flexiblen CAD-Konstruktionsfunktionen Konzepte in Windeseile zum Leben erwecken.","og_url":"https:\/\/solidedge.siemens.com\/de\/solutions\/products\/complete-product-development-portfolio\/designers-and-engineers\/","og_site_name":"Solid Edge","article_publisher":"https:\/\/www.facebook.com\/solidedge","article_modified_time":"2021-04-20T19:19:12+00:00","twitter_card":"summary_large_image","twitter_site":"@siemensplm","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"8 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/solidedge.siemens.com\/en\/#organization","name":"Siemens Digital Industries Software","url":"https:\/\/solidedge.siemens.com\/en\/","sameAs":["https:\/\/www.facebook.com\/solidedge","https:\/\/www.instagram.com\/siemens\/","https:\/\/www.linkedin.com\/company\/siemens-plm-software","https:\/\/www.youtube.com\/user\/PolarionSoftware","https:\/\/twitter.com\/siemensplm"],"logo":{"@type":"ImageObject","@id":"https:\/\/solidedge.siemens.com\/en\/#logo","inLanguage":"de-DE","url":"https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2018\/04\/logo-siemens-ifl@2x.png","contentUrl":"https:\/\/solidedge.siemens.com\/wp-content\/uploads\/2018\/04\/logo-siemens-ifl@2x.png","width":640,"height":270,"caption":"Siemens Digital Industries Software"},"image":{"@id":"https:\/\/solidedge.siemens.com\/en\/#logo"}},{"@type":"WebSite","@id":"https:\/\/solidedge.siemens.com\/en\/#website","url":"https:\/\/solidedge.siemens.com\/en\/","name":"Solid Edge","description":"Siemens Software","publisher":{"@id":"https:\/\/solidedge.siemens.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/solidedge.siemens.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/solidedge.siemens.com\/de\/solutions\/products\/complete-product-development-portfolio\/designers-and-engineers\/#webpage","url":"https:\/\/solidedge.siemens.com\/de\/solutions\/products\/complete-product-development-portfolio\/designers-and-engineers\/","name":"Konstrukteure und Ingenieure | 3D-CAD | Solid Edge","isPartOf":{"@id":"https:\/\/solidedge.siemens.com\/en\/#website"},"datePublished":"2019-04-01T14:22:21+00:00","dateModified":"2021-04-20T19:19:12+00:00","description":"Solid Edge hat die Antwort f\u00fcr Konstrukteure und Ingenieure. Erleben Sie in diesem Video hautnah, wie die schnellen, flexiblen CAD-Konstruktionsfunktionen Konzepte in Windeseile zum Leben erwecken.","breadcrumb":{"@id":"https:\/\/solidedge.siemens.com\/de\/solutions\/products\/complete-product-development-portfolio\/designers-and-engineers\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/solidedge.siemens.com\/de\/solutions\/products\/complete-product-development-portfolio\/designers-and-engineers\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/solidedge.siemens.com\/de\/solutions\/products\/complete-product-development-portfolio\/designers-and-engineers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/solidedge.siemens.com\/en\/home-7\/"},{"@type":"ListItem","position":2,"name":"L&ouml;sungen","item":"https:\/\/solidedge.siemens.com\/de\/solutions\/"},{"@type":"ListItem","position":3,"name":"Produkte","item":"https:\/\/solidedge.siemens.com\/de\/solutions\/products\/"},{"@type":"ListItem","position":4,"name":"Vollst&auml;ndiges Produktentwicklungsportfolio","item":"https:\/\/solidedge.siemens.com\/de\/solutions\/products\/complete-product-development-portfolio\/"},{"@type":"ListItem","position":5,"name":"Konstrukteure und Ingenieure"}]}]}},"_links":{"self":[{"href":"https:\/\/solidedge.siemens.com\/de\/wp-json\/wp\/v2\/pages\/2555"}],"collection":[{"href":"https:\/\/solidedge.siemens.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/solidedge.siemens.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/solidedge.siemens.com\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/solidedge.siemens.com\/de\/wp-json\/wp\/v2\/comments?post=2555"}],"version-history":[{"count":5,"href":"https:\/\/solidedge.siemens.com\/de\/wp-json\/wp\/v2\/pages\/2555\/revisions"}],"predecessor-version":[{"id":35480,"href":"https:\/\/solidedge.siemens.com\/de\/wp-json\/wp\/v2\/pages\/2555\/revisions\/35480"}],"up":[{"embeddable":true,"href":"https:\/\/solidedge.siemens.com\/de\/wp-json\/wp\/v2\/pages\/2774"}],"wp:attachment":[{"href":"https:\/\/solidedge.siemens.com\/de\/wp-json\/wp\/v2\/media?parent=2555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}